{"id":16713,"date":"2024-05-07T11:48:20","date_gmt":"2024-05-07T09:48:20","guid":{"rendered":"https:\/\/camping-labesse.com\/canvas-lodge\/"},"modified":"2026-07-12T10:25:08","modified_gmt":"2026-07-12T08:25:08","slug":"canvas-lodge","status":"publish","type":"page","link":"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/","title":{"rendered":"Canvas lodge"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16713\" class=\"elementor elementor-16713 elementor-12133\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66df347 e-con-full e-flex e-con e-parent\" data-id=\"66df347\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-dda494d e-con-full e-flex e-con e-child\" data-id=\"dda494d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:2248,&quot;url&quot;:&quot;https:\\\/\\\/camping-labesse.com\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/cabane-3.jpg&quot;}],&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d4db97 e-con-full moteur-reservation e-flex e-con e-child\" data-id=\"2d4db97\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d472de elementor-widget elementor-widget-text-editor\" data-id=\"3d472de\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Boek uw vakantie<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8330b5 elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"d8330b5\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t\n<thr-search-engine>\n<\/thr-search-engine>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a334568 e-flex e-con-boxed e-con e-parent\" data-id=\"a334568\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4817630 elementor-widget elementor-widget-heading\" data-id=\"4817630\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">  GESTERILISEERDE LODGE<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea1e7bd elementor-widget elementor-widget-heading\" data-id=\"ea1e7bd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Een bungalowtent huren in de Ari\u00e8ge<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bddf1d e-con-full e-flex e-con e-child\" data-id=\"3bddf1d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c3b8774 e-con-full e-flex e-con e-child\" data-id=\"c3b8774\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-249cdb5 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"249cdb5\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 14 2 C 11.25 2 9 4.25 9 7 C 9 9.75 11.25 12 14 12 C 16.75 12 19 9.75 19 7 C 19 4.25 16.75 2 14 2 Z M 35 2 C 32.25 2 30 4.25 30 7 C 30 9.75 32.25 12 35 12 C 37.75 12 40 9.75 40 7 C 40 4.25 37.75 2 35 2 Z M 14 4 C 15.667969 4 17 5.332031 17 7 C 17 8.667969 15.667969 10 14 10 C 12.332031 10 11 8.667969 11 7 C 11 5.332031 12.332031 4 14 4 Z M 35 4 C 36.667969 4 38 5.332031 38 7 C 38 8.667969 36.667969 10 35 10 C 33.332031 10 32 8.667969 32 7 C 32 5.332031 33.332031 4 35 4 Z M 9.5 13 C 6.476563 13 4 15.476563 4 18.5 L 4 30.8125 C 3.992188 30.875 3.992188 30.9375 4 31 C 3.996094 31.09375 4.007813 31.191406 4.03125 31.28125 C 4.179688 32.792969 5.453125 34 7 34 C 7.351563 34 7.683594 33.925781 8 33.8125 L 8 45.34375 C 8 46.804688 9.195313 48 10.65625 48 L 12.34375 48 C 12.988281 48 13.535156 47.699219 14 47.3125 C 14.464844 47.699219 15.011719 48 15.65625 48 L 17.34375 48 C 18.804688 48 20 46.804688 20 45.34375 L 20 38.8125 C 20.316406 38.925781 20.648438 39 21 39 L 21 45.5 C 21 46.867188 22.132813 48 23.5 48 L 26.5 48 C 27.867188 48 29 46.867188 29 45.5 L 29 39 C 29.351563 39 29.683594 38.925781 30 38.8125 L 30 45 C 30 46.644531 31.355469 48 33 48 C 33.765625 48 34.46875 47.699219 35 47.21875 C 35.53125 47.699219 36.234375 48 37 48 C 38.644531 48 40 46.644531 40 45 L 40 37 L 42.59375 37 C 43.25 37 43.871094 36.660156 44.21875 36.125 C 44.21875 36.113281 44.21875 36.105469 44.21875 36.09375 C 44.566406 35.554688 44.644531 34.910156 44.46875 34.3125 C 44.46875 34.300781 44.46875 34.292969 44.46875 34.28125 L 44.0625 33 C 45.074219 33 45.988281 32.507813 46.46875 31.71875 C 46.949219 30.929688 47.023438 29.945313 46.71875 29 C 45.800781 26.164063 42.6875 16.6875 42.6875 16.6875 C 42.5 16.109375 42.148438 15.253906 41.40625 14.46875 C 40.664063 13.683594 39.492188 13 38 13 L 36.0625 13 C 36.042969 13 36.019531 13 36 13 L 32 13 C 30.503906 13 29.335938 13.683594 28.59375 14.46875 C 28.214844 14.875 28.234375 15.511719 28.640625 15.890625 C 29.046875 16.269531 29.683594 16.25 30.0625 15.84375 C 30.515625 15.359375 31.074219 15 32 15 L 36 15 C 36.03125 15 36.0625 15 36.09375 15 L 38 15 C 38.921875 15 39.484375 15.363281 39.9375 15.84375 C 40.390625 16.324219 40.699219 16.957031 40.8125 17.3125 C 40.8125 17.3125 43.894531 26.765625 44.8125 29.59375 C 44.972656 30.085938 44.90625 30.453125 44.78125 30.65625 C 44.65625 30.859375 44.492188 31 44.0625 31 C 43.648438 31 43.289063 30.730469 43.15625 30.375 C 43.152344 30.367188 43.160156 30.351563 43.15625 30.34375 C 43.140625 30.246094 43.109375 30.152344 43.0625 30.0625 L 40.28125 21.6875 C 40.132813 21.222656 39.671875 20.929688 39.1875 21 C 38.890625 21.039063 38.628906 21.210938 38.472656 21.464844 C 38.3125 21.71875 38.277344 22.03125 38.375 22.3125 L 41.1875 30.75 C 41.207031 30.835938 41.238281 30.921875 41.28125 31 L 42.5625 34.90625 L 42.5625 34.9375 C 42.566406 34.96875 42.535156 34.984375 42.53125 35 L 35.0625 35 C 35.042969 35 35.019531 35 35 35 L 32 35 L 32 29 C 32 26.800781 30.199219 25 28 25 L 22 25 C 19.800781 25 18 26.800781 18 29 L 18 30.84375 C 18 30.875 18 30.90625 18 30.9375 L 18 45.34375 C 18 45.726563 17.722656 46 17.34375 46 L 15.65625 46 C 15.273438 46 15 45.726563 15 45.34375 L 15 32.65625 C 15.003906 32.367188 14.878906 32.09375 14.664063 31.902344 C 14.449219 31.710938 14.160156 31.621094 13.875 31.65625 C 13.371094 31.71875 12.996094 32.148438 13 32.65625 L 13 45.34375 C 13 45.726563 12.722656 46 12.34375 46 L 10.65625 46 C 10.273438 46 10 45.726563 10 45.34375 L 10 21 C 10.011719 20.710938 9.894531 20.433594 9.6875 20.238281 C 9.476563 20.039063 9.191406 19.941406 8.90625 19.96875 C 8.863281 19.976563 8.820313 19.988281 8.78125 20 C 8.316406 20.105469 7.988281 20.523438 8 21 L 8 30.84375 C 8 30.875 8 30.90625 8 30.9375 L 8 31 C 8 31.566406 7.566406 32 7 32 C 6.457031 32 6.03125 31.597656 6 31.0625 C 6 31.042969 6 31.019531 6 31 C 6.007813 30.9375 6.007813 30.875 6 30.8125 L 6 18.5 C 6 16.5625 7.558594 15 9.5 15 L 18.5 15 C 19.25 15 19.933594 15.226563 20.5 15.625 C 20.789063 15.867188 21.1875 15.925781 21.53125 15.777344 C 21.878906 15.628906 22.113281 15.300781 22.136719 14.925781 C 22.164063 14.550781 21.976563 14.195313 21.65625 14 C 20.765625 13.375 19.667969 13 18.5 13 Z M 25 16 C 22.800781 16 21 17.800781 21 20 C 21 22.199219 22.800781 24 25 24 C 27.199219 24 29 22.199219 29 20 C 29 17.800781 27.199219 16 25 16 Z M 25 18 C 26.117188 18 27 18.882813 27 20 C 27 21.117188 26.117188 22 25 22 C 23.882813 22 23 21.117188 23 20 C 23 18.882813 23.882813 18 25 18 Z M 22 27 L 28 27 C 29.117188 27 30 27.882813 30 29 L 30 35.8125 C 30 35.84375 30 35.875 30 35.90625 L 30 36 C 30 36.566406 29.566406 37 29 37 L 28 37 C 27.449219 37 27 37.449219 27 38 L 27 45.5 C 27 45.785156 26.785156 46 26.5 46 L 23.5 46 C 23.214844 46 23 45.785156 23 45.5 L 23 38 C 23 37.449219 22.550781 37 22 37 L 21 37 C 20.433594 37 20 36.566406 20 36 L 20 29 C 20 27.882813 20.882813 27 22 27 Z M 32 37 L 34 37 L 34 45 C 34 45.566406 33.566406 46 33 46 C 32.433594 46 32 45.566406 32 45 Z M 36 37 L 38 37 L 38 45 C 38 45.566406 37.566406 46 37 46 C 36.433594 46 36 45.566406 36 45 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f55129b elementor-widget elementor-widget-heading\" data-id=\"f55129b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4 personen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40e678a e-con-full e-flex e-con e-child\" data-id=\"40e678a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0853db2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0853db2\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 5 10 C 3.355469 10 2 11.355469 2 13 L 2 28.1875 C 2.003906 28.25 2.015625 28.3125 2.03125 28.375 C 2.03125 28.386719 2.03125 28.394531 2.03125 28.40625 C 1.582031 29.113281 1.214844 29.867188 0.9375 30.6875 C 0.316406 32.519531 0.0507813 34.621094 0 37 L 0 38 C 0 38.03125 0 38.0625 0 38.09375 L 0 50 L 7 50 L 7 46 C 7 45.167969 7.203125 44.734375 7.46875 44.46875 C 7.734375 44.203125 8.167969 44 9 44 L 41 44 C 41.832031 44 42.265625 44.203125 42.53125 44.46875 C 42.796875 44.734375 43 45.167969 43 46 L 43 50 L 50 50 L 50 38.15625 C 50.003906 38.105469 50.003906 38.050781 50 38 C 50 37.65625 50.007813 37.332031 50 37 C 49.949219 34.621094 49.683594 32.519531 49.0625 30.6875 C 48.785156 29.875 48.414063 29.136719 47.96875 28.4375 C 47.988281 28.355469 48 28.273438 48 28.1875 L 48 13 C 48 11.355469 46.644531 10 45 10 Z M 5 12 L 45 12 C 45.5625 12 46 12.4375 46 13 L 46 26.15625 C 45.753906 25.949219 45.492188 25.75 45.21875 25.5625 C 44.550781 25.101563 43.824219 24.671875 43 24.3125 L 43 20 C 43 19.296875 42.539063 18.75 42.03125 18.40625 C 41.523438 18.0625 40.902344 17.824219 40.125 17.625 C 38.570313 17.226563 36.386719 17 33.5 17 C 30.613281 17 28.429688 17.226563 26.875 17.625 C 26.117188 17.820313 25.5 18.042969 25 18.375 C 24.5 18.042969 23.882813 17.820313 23.125 17.625 C 21.570313 17.226563 19.386719 17 16.5 17 C 13.613281 17 11.429688 17.226563 9.875 17.625 C 9.097656 17.824219 8.476563 18.0625 7.96875 18.40625 C 7.460938 18.75 7 19.296875 7 20 L 7 24.3125 C 6.175781 24.671875 5.449219 25.101563 4.78125 25.5625 C 4.507813 25.75 4.246094 25.949219 4 26.15625 L 4 13 C 4 12.4375 4.4375 12 5 12 Z M 16.5 19 C 19.28125 19 21.34375 19.234375 22.625 19.5625 C 23.265625 19.726563 23.707031 19.925781 23.90625 20.0625 C 23.988281 20.117188 23.992188 20.125 24 20.125 L 24 22 C 17.425781 22.042969 12.558594 22.535156 9 23.625 L 9 20.125 C 9.007813 20.125 9.011719 20.117188 9.09375 20.0625 C 9.292969 19.925781 9.734375 19.726563 10.375 19.5625 C 11.65625 19.234375 13.71875 19 16.5 19 Z M 33.5 19 C 36.28125 19 38.34375 19.234375 39.625 19.5625 C 40.265625 19.726563 40.707031 19.925781 40.90625 20.0625 C 40.988281 20.117188 40.992188 20.125 41 20.125 L 41 23.625 C 37.441406 22.535156 32.574219 22.042969 26 22 L 26 20.125 C 26.007813 20.125 26.011719 20.117188 26.09375 20.0625 C 26.292969 19.925781 26.734375 19.726563 27.375 19.5625 C 28.65625 19.234375 30.71875 19 33.5 19 Z M 24.8125 24 C 24.917969 24.015625 25.019531 24.015625 25.125 24 C 25.15625 24 25.1875 24 25.21875 24 C 35.226563 24.015625 41.007813 25.0625 44.09375 27.1875 C 45.648438 28.257813 46.589844 29.585938 47.1875 31.34375 C 47.707031 32.875 47.917969 34.761719 47.96875 37 L 2.03125 37 C 2.082031 34.761719 2.292969 32.875 2.8125 31.34375 C 3.410156 29.585938 4.351563 28.257813 5.90625 27.1875 C 8.992188 25.058594 14.785156 24.011719 24.8125 24 Z M 2 39 L 48 39 L 48 48 L 45 48 L 45 46 C 45 44.832031 44.703125 43.765625 43.96875 43.03125 C 43.234375 42.296875 42.167969 42 41 42 L 9 42 C 7.832031 42 6.765625 42.296875 6.03125 43.03125 C 5.296875 43.765625 5 44.832031 5 46 L 5 48 L 2 48 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73489de elementor-widget elementor-widget-heading\" data-id=\"73489de\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2 slaapkamers<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f41d822 e-con-full e-flex e-con e-child\" data-id=\"f41d822\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b2357e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9b2357e\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 27.90625 -0.03125 C 27.863281 -0.0234375 27.820313 -0.0117188 27.78125 0 C 27.40625 0.0664063 27.105469 0.339844 27 0.703125 C 26.894531 1.070313 27.003906 1.460938 27.28125 1.71875 L 30.5625 5 L 4.4375 5 L 7.71875 1.71875 C 8.042969 1.417969 8.128906 0.941406 7.933594 0.546875 C 7.742188 0.148438 7.308594 -0.0703125 6.875 0 C 6.652344 0.0234375 6.441406 0.125 6.28125 0.28125 L 1.28125 5.28125 L 0.59375 6 L 1.28125 6.71875 L 6.28125 11.71875 C 6.679688 12.117188 7.320313 12.117188 7.71875 11.71875 C 8.117188 11.320313 8.117188 10.679688 7.71875 10.28125 L 4.4375 7 L 30.5625 7 L 27.28125 10.28125 C 26.882813 10.679688 26.882813 11.320313 27.28125 11.71875 C 27.679688 12.117188 28.320313 12.117188 28.71875 11.71875 L 33.71875 6.71875 L 34.40625 6 L 33.71875 5.28125 L 28.71875 0.28125 C 28.511719 0.0585938 28.210938 -0.0546875 27.90625 -0.03125 Z M 0 15 L 0 50 L 35 50 L 35 15 Z M 44 15.59375 L 43.28125 16.28125 L 38.28125 21.28125 C 37.882813 21.679688 37.882813 22.320313 38.28125 22.71875 C 38.679688 23.117188 39.320313 23.117188 39.71875 22.71875 L 43 19.4375 L 43 45.5625 L 39.71875 42.28125 C 39.511719 42.058594 39.210938 41.945313 38.90625 41.96875 C 38.863281 41.976563 38.820313 41.988281 38.78125 42 C 38.40625 42.066406 38.105469 42.339844 38 42.703125 C 37.894531 43.070313 38.003906 43.460938 38.28125 43.71875 L 43.28125 48.71875 L 44 49.40625 L 44.71875 48.71875 L 49.71875 43.71875 C 50.117188 43.320313 50.117188 42.679688 49.71875 42.28125 C 49.320313 41.882813 48.679688 41.882813 48.28125 42.28125 L 45 45.5625 L 45 19.4375 L 48.28125 22.71875 C 48.679688 23.117188 49.320313 23.117188 49.71875 22.71875 C 50.117188 22.320313 50.117188 21.679688 49.71875 21.28125 L 44.71875 16.28125 Z M 2 17 L 33 17 L 33 48 L 2 48 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90d9b69 elementor-widget elementor-widget-heading\" data-id=\"90d9b69\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">35 m\u00b2<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9430282 e-flex e-con-boxed e-con e-child\" data-id=\"9430282\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b57d813 e-con-full e-flex e-con e-child\" data-id=\"b57d813\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd4bbb9 elementor-widget elementor-widget-heading\" data-id=\"bd4bbb9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">LODGE OP PALEN OP CAMPING DE LA BESSE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e58f103 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e58f103\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-786d7da elementor-widget elementor-widget-text-editor\" data-id=\"786d7da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Deze kleine houten hutten op palen zijn van alle gemakken voorzien. Ze bevinden zich in het lager gelegen deel van de camping en bieden je de mogelijkheid om comfortabel van de natuur te genieten. <\/p><p>Geen sanitaire voorzieningen, maar elektriciteit betekent dat je gemakkelijk kunt koken&#8230;.<\/p><p>Het overdekte terras is een leefruimte op zich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b13301 e-con-full e-flex e-con e-child\" data-id=\"6b13301\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1e258c elementor-arrows-position-outside slider-small elementor-widget elementor-widget-image-carousel\" data-id=\"c1e258c\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 van 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg\" alt=\"Location de Cabane Lodge en Ari\u00e8ge (Camping de La Besse)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 van 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-2-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg\" alt=\"Location de Cabane Lodge en Ari\u00e8ge (Camping de La Besse)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 van 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-3-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg\" alt=\"Cabane-Lodge - Location de cvabane eau Camping de La Besse en Arti\u00e8ge\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 van 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-chambre-adulte-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg\" alt=\"Location de Cabane Lodge en Ari\u00e8ge (Camping de La Besse)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 van 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-chambre-enfant-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg\" alt=\"Location de Cabane Lodge en Ari\u00e8ge (Camping de La Besse)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-574ed61 e-flex e-con-boxed e-con e-child\" data-id=\"574ed61\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26867d5 elementor-widget elementor-widget-heading\" data-id=\"26867d5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Beschrijving van de stacaravan<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e05c547 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e05c547\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b9e6c9 e-flex e-con-boxed e-con e-child\" data-id=\"4b9e6c9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a6a34e4 e-con-full e-flex e-con e-child\" data-id=\"a6a34e4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbecedc elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cbecedc\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 5 10 C 3.355469 10 2 11.355469 2 13 L 2 28.1875 C 2.003906 28.25 2.015625 28.3125 2.03125 28.375 C 2.03125 28.386719 2.03125 28.394531 2.03125 28.40625 C 1.582031 29.113281 1.214844 29.867188 0.9375 30.6875 C 0.316406 32.519531 0.0507813 34.621094 0 37 L 0 38 C 0 38.03125 0 38.0625 0 38.09375 L 0 50 L 7 50 L 7 46 C 7 45.167969 7.203125 44.734375 7.46875 44.46875 C 7.734375 44.203125 8.167969 44 9 44 L 41 44 C 41.832031 44 42.265625 44.203125 42.53125 44.46875 C 42.796875 44.734375 43 45.167969 43 46 L 43 50 L 50 50 L 50 38.15625 C 50.003906 38.105469 50.003906 38.050781 50 38 C 50 37.65625 50.007813 37.332031 50 37 C 49.949219 34.621094 49.683594 32.519531 49.0625 30.6875 C 48.785156 29.875 48.414063 29.136719 47.96875 28.4375 C 47.988281 28.355469 48 28.273438 48 28.1875 L 48 13 C 48 11.355469 46.644531 10 45 10 Z M 5 12 L 45 12 C 45.5625 12 46 12.4375 46 13 L 46 26.15625 C 45.753906 25.949219 45.492188 25.75 45.21875 25.5625 C 44.550781 25.101563 43.824219 24.671875 43 24.3125 L 43 20 C 43 19.296875 42.539063 18.75 42.03125 18.40625 C 41.523438 18.0625 40.902344 17.824219 40.125 17.625 C 38.570313 17.226563 36.386719 17 33.5 17 C 30.613281 17 28.429688 17.226563 26.875 17.625 C 26.117188 17.820313 25.5 18.042969 25 18.375 C 24.5 18.042969 23.882813 17.820313 23.125 17.625 C 21.570313 17.226563 19.386719 17 16.5 17 C 13.613281 17 11.429688 17.226563 9.875 17.625 C 9.097656 17.824219 8.476563 18.0625 7.96875 18.40625 C 7.460938 18.75 7 19.296875 7 20 L 7 24.3125 C 6.175781 24.671875 5.449219 25.101563 4.78125 25.5625 C 4.507813 25.75 4.246094 25.949219 4 26.15625 L 4 13 C 4 12.4375 4.4375 12 5 12 Z M 16.5 19 C 19.28125 19 21.34375 19.234375 22.625 19.5625 C 23.265625 19.726563 23.707031 19.925781 23.90625 20.0625 C 23.988281 20.117188 23.992188 20.125 24 20.125 L 24 22 C 17.425781 22.042969 12.558594 22.535156 9 23.625 L 9 20.125 C 9.007813 20.125 9.011719 20.117188 9.09375 20.0625 C 9.292969 19.925781 9.734375 19.726563 10.375 19.5625 C 11.65625 19.234375 13.71875 19 16.5 19 Z M 33.5 19 C 36.28125 19 38.34375 19.234375 39.625 19.5625 C 40.265625 19.726563 40.707031 19.925781 40.90625 20.0625 C 40.988281 20.117188 40.992188 20.125 41 20.125 L 41 23.625 C 37.441406 22.535156 32.574219 22.042969 26 22 L 26 20.125 C 26.007813 20.125 26.011719 20.117188 26.09375 20.0625 C 26.292969 19.925781 26.734375 19.726563 27.375 19.5625 C 28.65625 19.234375 30.71875 19 33.5 19 Z M 24.8125 24 C 24.917969 24.015625 25.019531 24.015625 25.125 24 C 25.15625 24 25.1875 24 25.21875 24 C 35.226563 24.015625 41.007813 25.0625 44.09375 27.1875 C 45.648438 28.257813 46.589844 29.585938 47.1875 31.34375 C 47.707031 32.875 47.917969 34.761719 47.96875 37 L 2.03125 37 C 2.082031 34.761719 2.292969 32.875 2.8125 31.34375 C 3.410156 29.585938 4.351563 28.257813 5.90625 27.1875 C 8.992188 25.058594 14.785156 24.011719 24.8125 24 Z M 2 39 L 48 39 L 48 48 L 45 48 L 45 46 C 45 44.832031 44.703125 43.765625 43.96875 43.03125 C 43.234375 42.296875 42.167969 42 41 42 L 9 42 C 7.832031 42 6.765625 42.296875 6.03125 43.03125 C 5.296875 43.765625 5 44.832031 5 46 L 5 48 L 2 48 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-030f7e5 elementor-widget elementor-widget-heading\" data-id=\"030f7e5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1 bed 140cm<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54d2df1 e-con-full e-flex e-con e-child\" data-id=\"54d2df1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1662157 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1662157\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 10 9 C 8.355469 9 7 10.355469 7 12 L 7 42 C 7 42.550781 7.449219 43 8 43 L 12 43 C 12.550781 43 13 42.550781 13 42 L 13 40 C 13 39.445313 13.445313 39 14 39 L 36 39 C 36.554688 39 37 39.445313 37 40 L 37 42 C 37 42.550781 37.449219 43 38 43 L 42 43 C 42.550781 43 43 42.550781 43 42 L 43 12 C 43 10.355469 41.644531 9 40 9 Z M 10 11 L 40 11 C 40.554688 11 41 11.445313 41 12 L 41 22.1875 C 40.683594 22.074219 40.351563 22 40 22 L 38 22 L 38 20 C 38.003906 19.789063 37.9375 19.578125 37.8125 19.40625 C 37.8125 19.40625 36.886719 18.207031 34.875 17.125 C 32.863281 16.042969 29.695313 15 25 15 C 20.304688 15 17.136719 16.042969 15.125 17.125 C 13.113281 18.207031 12.1875 19.40625 12.1875 19.40625 C 12.0625 19.578125 11.996094 19.789063 12 20 L 12 22 L 10 22 C 9.648438 22 9.316406 22.074219 9 22.1875 L 9 12 C 9 11.445313 9.445313 11 10 11 Z M 25 17 C 29.402344 17 32.222656 17.957031 33.9375 18.875 C 35.503906 19.714844 35.910156 20.316406 36 20.4375 L 36 22 L 14 22 L 14 20.4375 C 14.089844 20.316406 14.496094 19.714844 16.0625 18.875 C 17.777344 17.957031 20.597656 17 25 17 Z M 10 24 L 40 24 C 40.554688 24 41 24.445313 41 25 L 41 41 L 39 41 L 39 40 C 39 38.355469 37.644531 37 36 37 L 14 37 C 12.355469 37 11 38.355469 11 40 L 11 41 L 9 41 L 9 25 C 9 24.445313 9.445313 24 10 24 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6869a9b elementor-widget elementor-widget-heading\" data-id=\"6869a9b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2 bedden 90cm<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95a35a1 e-con-full e-flex e-con e-child\" data-id=\"95a35a1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75b5a27 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"75b5a27\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 13.5 8 C 7.6581204 8 3 13.191188 3 19.458984 C 3 19.568222 3.0019531 19.581238 3.0019531 19.5 C 3.0019531 19.418762 3 19.431778 3 19.541016 C 3 19.636486 3.0115227 19.729262 3.0136719 19.824219 A 1.0001 1.0001 0 0 0 3 20 L 3 31 A 1.0001 1.0001 0 0 0 3.1152344 31.460938 C 3.5546887 37.29289 7.9553684 42 13.5 42 C 16.445576 42 18.359411 41.163996 19.957031 40.410156 C 21.554652 39.656316 22.807788 39.011719 24.96875 39.011719 C 27.636052 39.011719 28.872615 39.653311 30.353516 40.398438 C 31.834416 41.143563 33.568909 42 36.5 42 C 42.04401 42 46.444457 37.293932 46.884766 31.462891 A 1.0001 1.0001 0 0 0 47 31 L 47 20 A 1.0001 1.0001 0 0 0 46.986328 19.830078 C 46.988567 19.733172 47 19.638457 47 19.541016 C 47 19.431778 46.998047 19.418766 46.998047 19.5 C 46.998047 19.58124 47 19.568224 47 19.458984 C 47 13.191196 42.34188 8 36.5 8 C 33.568909 8 31.834416 8.8564365 30.353516 9.6015625 C 28.872615 10.346689 27.636052 10.988281 24.96875 10.988281 C 22.807788 10.988281 21.554652 10.343684 19.957031 9.5898438 C 18.359411 8.836004 16.445576 8 13.5 8 z M 13.5 10 C 16.085424 10 17.534886 10.658276 19.103516 11.398438 C 20.672145 12.138597 22.387712 12.988281 24.96875 12.988281 C 27.986448 12.988281 29.765557 12.135593 31.253906 11.386719 C 32.742256 10.637845 33.931091 10 36.5 10 C 41.15212 10 45 14.172781 45 19.458984 C 45 19.377744 44.998047 19.39076 44.998047 19.5 C 44.998047 19.609238 45 19.62225 45 19.541016 C 45 24.827211 41.15212 29 36.5 29 C 33.931091 29 32.742256 28.362155 31.253906 27.613281 C 29.765557 26.864407 27.986448 26.011719 24.96875 26.011719 C 22.387712 26.011719 20.672145 26.861402 19.103516 27.601562 C 17.534886 28.341724 16.085424 29 13.5 29 C 8.8478796 29 5 24.827219 5 19.541016 C 5 19.622254 5.0019531 19.609238 5.0019531 19.5 C 5.0019531 19.390762 5 19.377746 5 19.458984 C 5 14.172781 8.8478796 10 13.5 10 z M 11 14 A 1 1 0 0 0 10 15 A 1 1 0 0 0 11 16 A 1 1 0 0 0 12 15 A 1 1 0 0 0 11 14 z M 39 14 A 1 1 0 0 0 38 15 A 1 1 0 0 0 39 16 A 1 1 0 0 0 40 15 A 1 1 0 0 0 39 14 z M 17 15 A 1 1 0 0 0 16 16 A 1 1 0 0 0 17 17 A 1 1 0 0 0 18 16 A 1 1 0 0 0 17 15 z M 33 15 A 1 1 0 0 0 32 16 A 1 1 0 0 0 33 17 A 1 1 0 0 0 34 16 A 1 1 0 0 0 33 15 z M 25 17 A 1 1 0 0 0 24 18 A 1 1 0 0 0 25 19 A 1 1 0 0 0 26 18 A 1 1 0 0 0 25 17 z M 11 20 A 1 1 0 0 0 10 21 A 1 1 0 0 0 11 22 A 1 1 0 0 0 12 21 A 1 1 0 0 0 11 20 z M 41 20 A 1 1 0 0 0 40 21 A 1 1 0 0 0 41 22 A 1 1 0 0 0 42 21 A 1 1 0 0 0 41 20 z M 19 21 A 1 1 0 0 0 18 22 A 1 1 0 0 0 19 23 A 1 1 0 0 0 20 22 A 1 1 0 0 0 19 21 z M 35 22 A 1 1 0 0 0 34 23 A 1 1 0 0 0 35 24 A 1 1 0 0 0 36 23 A 1 1 0 0 0 35 22 z M 5 26.242188 C 6.9005611 29.109788 9.9812582 31 13.5 31 C 16.445576 31 18.359411 30.163996 19.957031 29.410156 C 21.554652 28.656316 22.807788 28.011719 24.96875 28.011719 C 27.636052 28.011719 28.872615 28.65331 30.353516 29.398438 C 31.834416 30.143564 33.568909 31 36.5 31 C 40.018742 31 43.099439 29.109788 45 26.242188 L 45 30.802734 A 1.0001 1.0001 0 0 0 44.980469 30.960938 C 44.779281 36.047311 41.026551 40 36.5 40 C 33.931091 40 32.742256 39.362155 31.253906 38.613281 C 29.765557 37.864407 27.986448 37.011719 24.96875 37.011719 C 22.387712 37.011719 20.672145 37.861402 19.103516 38.601562 C 17.534886 39.341724 16.085424 40 13.5 40 C 8.973449 40 5.2207183 36.047311 5.0195312 30.960938 A 1.0001 1.0001 0 0 0 5 30.802734 L 5 26.242188 z M 27 32 A 1 1 0 0 0 26 33 A 1 1 0 0 0 27 34 A 1 1 0 0 0 28 33 A 1 1 0 0 0 27 32 z M 42 32 A 1 1 0 0 0 41 33 A 1 1 0 0 0 42 34 A 1 1 0 0 0 43 33 A 1 1 0 0 0 42 32 z M 9 33 A 1 1 0 0 0 8 34 A 1 1 0 0 0 9 35 A 1 1 0 0 0 10 34 A 1 1 0 0 0 9 33 z M 19 33 A 1 1 0 0 0 18 34 A 1 1 0 0 0 19 35 A 1 1 0 0 0 20 34 A 1 1 0 0 0 19 33 z M 35 35 A 1 1 0 0 0 34 36 A 1 1 0 0 0 35 37 A 1 1 0 0 0 36 36 A 1 1 0 0 0 35 35 z M 13 36 A 1 1 0 0 0 12 37 A 1 1 0 0 0 13 38 A 1 1 0 0 0 14 37 A 1 1 0 0 0 13 36 z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1b50a6 elementor-widget elementor-widget-heading\" data-id=\"f1b50a6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Huishoudkit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1f4177 elementor-widget elementor-widget-text-editor\" data-id=\"c1f4177\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSpons, afwasmiddel, multifunctioneel product, enz.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-183ec29 e-con-full e-flex e-con e-child\" data-id=\"183ec29\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1820d10 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1820d10\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 10 0 C 8.355469 0 7 1.355469 7 3 L 7 18.6875 C 6.941406 18.882813 6.941406 19.085938 7 19.28125 L 7 44 C 7 45.644531 8.355469 47 10 47 L 10 48 C 10 49.09375 10.90625 50 12 50 L 15 50 C 16.09375 50 17 49.09375 17 48 L 17 47 L 33 47 L 33 48 C 33 49.09375 33.90625 50 35 50 L 38 50 C 39.09375 50 40 49.09375 40 48 L 40 47 C 41.644531 47 43 45.644531 43 44 L 43 19.1875 C 43.027344 19.054688 43.027344 18.914063 43 18.78125 L 43 3 C 43 1.355469 41.644531 0 40 0 Z M 10 2 L 40 2 C 40.5625 2 41 2.4375 41 3 L 41 18 L 9 18 L 9 3 C 9 2.4375 9.4375 2 10 2 Z M 13.90625 5.96875 C 13.863281 5.976563 13.820313 5.988281 13.78125 6 C 13.316406 6.105469 12.988281 6.523438 13 7 L 13 14 C 12.996094 14.359375 13.183594 14.695313 13.496094 14.878906 C 13.808594 15.058594 14.191406 15.058594 14.503906 14.878906 C 14.816406 14.695313 15.003906 14.359375 15 14 L 15 7 C 15.011719 6.710938 14.894531 6.433594 14.6875 6.238281 C 14.476563 6.039063 14.191406 5.941406 13.90625 5.96875 Z M 9 20 L 41 20 L 41 44 C 41 44.5625 40.5625 45 40 45 L 10 45 C 9.4375 45 9 44.5625 9 44 Z M 13.90625 22.96875 C 13.863281 22.976563 13.820313 22.988281 13.78125 23 C 13.316406 23.105469 12.988281 23.523438 13 24 L 13 31 C 12.996094 31.359375 13.183594 31.695313 13.496094 31.878906 C 13.808594 32.058594 14.191406 32.058594 14.503906 31.878906 C 14.816406 31.695313 15.003906 31.359375 15 31 L 15 24 C 15.011719 23.710938 14.894531 23.433594 14.6875 23.238281 C 14.476563 23.039063 14.191406 22.941406 13.90625 22.96875 Z M 12 47 L 15 47 L 15 48 L 12 48 Z M 35 47 L 38 47 L 38 48 L 35 48 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30d1a6e elementor-widget elementor-widget-heading\" data-id=\"30d1a6e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">FrigoTop<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-091b0fd e-con-full e-flex e-con e-child\" data-id=\"091b0fd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a36fcf elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9a36fcf\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 3 8 C 1.355469 8 0 9.355469 0 11 L 0 39 C 0 40.644531 1.355469 42 3 42 L 5 42 L 5 43 C 5 44.09375 5.90625 45 7 45 L 10 45 C 11.09375 45 12 44.09375 12 43 L 12 42 L 38 42 L 38 43 C 38 44.09375 38.90625 45 40 45 L 43 45 C 44.09375 45 45 44.09375 45 43 L 45 42 L 47 42 C 48.644531 42 50 40.644531 50 39 L 50 11 C 50 9.355469 48.644531 8 47 8 Z M 3 10 L 47 10 C 47.5625 10 48 10.4375 48 11 L 48 39 C 48 39.5625 47.5625 40 47 40 L 39.1875 40 C 39.054688 39.972656 38.914063 39.972656 38.78125 40 L 6.1875 40 C 6.054688 39.972656 5.914063 39.972656 5.78125 40 L 3 40 C 2.4375 40 2 39.5625 2 39 L 2 11 C 2 10.4375 2.4375 10 3 10 Z M 5 13 L 5 37 L 40 37 L 40 13 Z M 7 15 L 38 15 L 38 35 L 7 35 Z M 44 16 C 42.894531 16 42 16.894531 42 18 C 42 19.105469 42.894531 20 44 20 C 45.105469 20 46 19.105469 46 18 C 46 16.894531 45.105469 16 44 16 Z M 34.15625 19.9375 C 33.957031 19.933594 33.761719 19.988281 33.59375 20.09375 C 33.59375 20.09375 28.964844 22 26.125 22 C 24.707031 22 23.75 21.59375 22.59375 21.09375 C 21.4375 20.59375 20.066406 20 18.21875 20 C 14.523438 20 10.5625 22.09375 10.5625 22.09375 C 10.0625 22.335938 9.851563 22.9375 10.09375 23.4375 C 10.335938 23.9375 10.9375 24.148438 11.4375 23.90625 C 11.4375 23.90625 15.332031 22 18.21875 22 C 19.664063 22 20.628906 22.40625 21.78125 22.90625 C 22.933594 23.40625 24.296875 24 26.125 24 C 29.785156 24 34.40625 21.90625 34.40625 21.90625 C 34.894531 21.78125 35.214844 21.3125 35.148438 20.8125 C 35.085938 20.3125 34.660156 19.9375 34.15625 19.9375 Z M 44 23 C 42.894531 23 42 23.894531 42 25 C 42 26.105469 42.894531 27 44 27 C 45.105469 27 46 26.105469 46 25 C 46 23.894531 45.105469 23 44 23 Z M 34.15625 25.9375 C 33.957031 25.933594 33.761719 25.988281 33.59375 26.09375 C 33.59375 26.09375 28.964844 28 26.125 28 C 24.707031 28 23.75 27.59375 22.59375 27.09375 C 21.4375 26.59375 20.066406 26 18.21875 26 C 14.523438 26 10.5625 28.09375 10.5625 28.09375 C 10.0625 28.335938 9.851563 28.9375 10.09375 29.4375 C 10.335938 29.9375 10.9375 30.148438 11.4375 29.90625 C 11.4375 29.90625 15.332031 28 18.21875 28 C 19.664063 28 20.628906 28.40625 21.78125 28.90625 C 22.933594 29.40625 24.296875 30 26.125 30 C 29.785156 30 34.40625 27.90625 34.40625 27.90625 C 34.894531 27.78125 35.214844 27.3125 35.148438 26.8125 C 35.085938 26.3125 34.660156 25.9375 34.15625 25.9375 Z M 44 30 C 42.894531 30 42 30.894531 42 32 C 42 33.105469 42.894531 34 44 34 C 45.105469 34 46 33.105469 46 32 C 46 30.894531 45.105469 30 44 30 Z M 7 42 L 10 42 L 10 43 L 7 43 Z M 40 42 L 43 42 L 43 43 L 40 43 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c40291 elementor-widget elementor-widget-heading\" data-id=\"7c40291\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Magnetron<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05ced74 e-con-full e-flex e-con e-child\" data-id=\"05ced74\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85c9e39 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"85c9e39\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 13.46875 0 C 8.777344 0 4.9375 3.816406 4.9375 8.5 C 4.9375 13.183594 8.777344 17 13.46875 17 L 16 17 L 16 22 L 21 22 L 21 17 L 32 17 L 32 41 L 25.8125 41 C 26.140625 40.535156 26.464844 39.980469 26.78125 39.3125 C 27.992188 36.75 29 32.601563 29 26 C 29 25.449219 28.550781 25 28 25 L 9 25 C 8.96875 25 8.9375 25 8.90625 25 C 8.390625 25.046875 7.996094 25.480469 8 26 C 8 26.792969 8.003906 27.558594 8.03125 28.28125 C 7.585938 28.113281 7.078125 28 6.5 28 C 4.027344 28 2 30.027344 2 32.5 C 2 34.972656 4.027344 37 6.5 37 L 9.34375 37 C 9.617188 37.890625 9.90625 38.648438 10.21875 39.3125 C 10.535156 39.980469 10.859375 40.535156 11.1875 41 L 7.5 41 C 6.132813 41 5 42.132813 5 43.5 L 5 47.5 C 5 48.867188 6.132813 50 7.5 50 L 45.5 50 C 47.421875 50 49 48.421875 49 46.5 L 49 42 C 49.003906 41.949219 49.003906 41.894531 49 41.84375 L 44.4375 14.5625 C 46.019531 13.019531 47 10.871094 47 8.5 C 47 3.816406 43.160156 0 38.46875 0 Z M 13.46875 2 L 38.46875 2 C 42.082031 2 45 4.898438 45 8.5 C 45 12.101563 42.082031 15 38.46875 15 L 17.1875 15 C 17.054688 14.972656 16.914063 14.972656 16.78125 15 L 13.46875 15 C 9.855469 15 6.9375 12.101563 6.9375 8.5 C 6.9375 4.898438 9.855469 2 13.46875 2 Z M 42.625 15.90625 L 47 42.15625 L 47 46.5 C 47 47.339844 46.339844 48 45.5 48 L 7.5 48 C 7.214844 48 7 47.785156 7 47.5 L 7 43.5 C 7 43.214844 7.214844 43 7.5 43 L 33 43 C 33.550781 43 34 42.550781 34 42 L 34 17 L 38.46875 17 C 39.976563 17 41.394531 16.597656 42.625 15.90625 Z M 18 17 L 19 17 L 19 20 L 18 20 Z M 10.09375 27 L 26.90625 27 C 26.792969 32.6875 25.9375 36.386719 24.96875 38.4375 C 24.453125 39.53125 23.933594 40.214844 23.53125 40.59375 C 23.226563 40.878906 22.957031 40.972656 22.9375 41 L 14.0625 41 C 14.042969 40.972656 13.773438 40.878906 13.46875 40.59375 C 13.066406 40.214844 12.546875 39.53125 12.03125 38.4375 C 11.0625 36.386719 10.207031 32.6875 10.09375 27 Z M 6.5 30 C 7.308594 30 7.875 30.394531 8.21875 30.71875 C 8.363281 32.347656 8.574219 33.757813 8.84375 35 L 6.5 35 C 5.109375 35 4 33.890625 4 32.5 C 4 31.109375 5.109375 30 6.5 30 Z M 40 35 C 38.894531 35 38 35.894531 38 37 C 38 38.105469 38.894531 39 40 39 C 41.105469 39 42 38.105469 42 37 C 42 35.894531 41.105469 35 40 35 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e287669 elementor-widget elementor-widget-heading\" data-id=\"e287669\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Filterkoffiezetapparaat<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95ab1e5 e-con-full e-flex e-con e-child\" data-id=\"95ab1e5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fca88b5 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"fca88b5\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 34 0 C 14.96875 0 7.179688 5.792969 3.1875 11.4375 C 3.03125 11.671875 2.976563 11.957031 3.042969 12.230469 C 3.109375 12.503906 3.285156 12.738281 3.53125 12.875 C 3.53125 12.875 4.304688 13.277344 5.1875 14.5 C 6.070313 15.722656 7 17.730469 7 21 L 7 44 C 5.355469 44 4 45.355469 4 47 L 4 50 L 43 50 L 43 47 C 43 45.355469 41.644531 44 40 44 L 39 44 L 39 37.53125 L 43.5 34.84375 C 43.902344 34.597656 44.078125 34.101563 43.917969 33.65625 C 43.761719 33.210938 43.3125 32.9375 42.84375 33 C 42.71875 33.03125 42.605469 33.082031 42.5 33.15625 L 39 35.25 L 39 29.25 C 39.339844 28.769531 45 20.714844 45 12 C 45 9.121094 44.34375 6.148438 42.59375 3.84375 C 40.84375 1.539063 37.96875 0 34 0 Z M 34 2 C 37.472656 2 39.609375 3.226563 41 5.0625 C 42.390625 6.898438 43 9.433594 43 12 C 43 20.035156 37.1875 28.4375 37.1875 28.4375 C 37.070313 28.601563 37.003906 28.796875 37 29 L 37 36.5625 C 36.796875 36.886719 36.796875 37.300781 37 37.625 L 37 44 L 9 44 L 9 21 C 9 17.347656 7.929688 14.859375 6.8125 13.3125 C 6.335938 12.652344 5.851563 12.230469 5.4375 11.875 C 9.238281 6.910156 16.199219 2 34 2 Z M 34.40625 5 C 33.394531 5 32.558594 5.085938 31.875 5.65625 C 31.191406 6.226563 31 7.117188 31 8 L 31 22 C 31 22.472656 31.097656 22.941406 31.40625 23.34375 C 31.714844 23.746094 32.253906 24 32.75 24 C 34.300781 24 35.707031 22.8125 36.90625 20.8125 C 38.105469 18.8125 39 15.886719 39 12 L 39 9 C 39 7.714844 38.324219 6.660156 37.4375 6 C 36.550781 5.339844 35.460938 5 34.40625 5 Z M 34.40625 7 C 35.019531 7 35.726563 7.226563 36.21875 7.59375 C 36.710938 7.960938 37 8.390625 37 9 L 37 12 C 37 15.574219 36.171875 18.144531 35.1875 19.78125 C 34.332031 21.203125 33.398438 21.734375 33 21.875 L 33 8 C 33 7.355469 33.101563 7.234375 33.15625 7.1875 C 33.210938 7.140625 33.5625 7 34.40625 7 Z M 22 17 C 18.699219 17 16 19.699219 16 23 L 16 23.53125 C 15.867188 23.808594 15.867188 24.128906 16 24.40625 L 16 28.53125 C 15.867188 28.808594 15.867188 29.128906 16 29.40625 L 16 33.53125 C 15.867188 33.808594 15.867188 34.128906 16 34.40625 L 16 35 C 16 38.300781 18.699219 41 22 41 C 25.300781 41 28 38.300781 28 35 L 28 23 C 28 19.699219 25.300781 17 22 17 Z M 22 19 C 24.21875 19 26 20.78125 26 23 L 26 35 C 26 37.21875 24.21875 39 22 39 C 19.78125 39 18 37.21875 18 35 L 22 35 C 22.359375 35.003906 22.695313 34.816406 22.878906 34.503906 C 23.058594 34.191406 23.058594 33.808594 22.878906 33.496094 C 22.695313 33.183594 22.359375 32.996094 22 33 L 18 33 L 18 30 L 22 30 C 22.359375 30.003906 22.695313 29.816406 22.878906 29.503906 C 23.058594 29.191406 23.058594 28.808594 22.878906 28.496094 C 22.695313 28.183594 22.359375 27.996094 22 28 L 18 28 L 18 25 L 22 25 C 22.359375 25.003906 22.695313 24.816406 22.878906 24.503906 C 23.058594 24.191406 23.058594 23.808594 22.878906 23.496094 C 22.695313 23.183594 22.359375 22.996094 22 23 L 18 23 C 18 20.78125 19.78125 19 22 19 Z M 7 46 L 40 46 C 40.5625 46 41 46.4375 41 47 L 41 48 L 6 48 L 6 47 C 6 46.4375 6.4375 46 7 46 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f7f5a8 elementor-widget elementor-widget-heading\" data-id=\"3f7f5a8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ketel<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf2e739 e-con-full e-flex e-con e-child\" data-id=\"bf2e739\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc5cbca elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"dc5cbca\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 18.90625 1.96875 C 18.863281 1.976563 18.820313 1.988281 18.78125 2 C 18.40625 2.066406 18.105469 2.339844 18 2.703125 C 17.894531 3.070313 18.003906 3.460938 18.28125 3.71875 C 19.011719 4.441406 19.050781 4.753906 19 5.0625 C 18.949219 5.371094 18.652344 5.835938 18.21875 6.40625 C 17.785156 6.976563 17.195313 7.648438 17.03125 8.625 C 16.867188 9.601563 17.277344 10.722656 18.28125 11.71875 C 18.679688 12.117188 19.320313 12.117188 19.71875 11.71875 C 20.117188 11.320313 20.117188 10.679688 19.71875 10.28125 C 18.992188 9.558594 18.949219 9.246094 19 8.9375 C 19.050781 8.628906 19.378906 8.164063 19.8125 7.59375 C 20.246094 7.023438 20.804688 6.351563 20.96875 5.375 C 21.132813 4.398438 20.722656 3.277344 19.71875 2.28125 C 19.511719 2.058594 19.210938 1.945313 18.90625 1.96875 Z M 24.90625 1.96875 C 24.863281 1.976563 24.820313 1.988281 24.78125 2 C 24.40625 2.066406 24.105469 2.339844 24 2.703125 C 23.894531 3.070313 24.003906 3.460938 24.28125 3.71875 C 25.011719 4.441406 25.050781 4.753906 25 5.0625 C 24.949219 5.371094 24.652344 5.835938 24.21875 6.40625 C 23.785156 6.976563 23.195313 7.648438 23.03125 8.625 C 22.867188 9.601563 23.277344 10.722656 24.28125 11.71875 C 24.679688 12.117188 25.320313 12.117188 25.71875 11.71875 C 26.117188 11.320313 26.117188 10.679688 25.71875 10.28125 C 24.992188 9.558594 24.949219 9.246094 25 8.9375 C 25.050781 8.628906 25.378906 8.164063 25.8125 7.59375 C 26.246094 7.023438 26.804688 6.351563 26.96875 5.375 C 27.132813 4.398438 26.722656 3.277344 25.71875 2.28125 C 25.511719 2.058594 25.210938 1.945313 24.90625 1.96875 Z M 30.90625 1.96875 C 30.863281 1.976563 30.820313 1.988281 30.78125 2 C 30.40625 2.066406 30.105469 2.339844 30 2.703125 C 29.894531 3.070313 30.003906 3.460938 30.28125 3.71875 C 31.011719 4.441406 31.050781 4.753906 31 5.0625 C 30.949219 5.371094 30.652344 5.835938 30.21875 6.40625 C 29.785156 6.976563 29.195313 7.648438 29.03125 8.625 C 28.867188 9.601563 29.277344 10.722656 30.28125 11.71875 C 30.679688 12.117188 31.320313 12.117188 31.71875 11.71875 C 32.117188 11.320313 32.117188 10.679688 31.71875 10.28125 C 30.992188 9.558594 30.949219 9.246094 31 8.9375 C 31.050781 8.628906 31.378906 8.164063 31.8125 7.59375 C 32.246094 7.023438 32.804688 6.351563 32.96875 5.375 C 33.132813 4.398438 32.722656 3.277344 31.71875 2.28125 C 31.511719 2.058594 31.210938 1.945313 30.90625 1.96875 Z M 7 14 L 7 15 C 7 21.566406 10.550781 27.292969 15.8125 30.4375 L 11.03125 46.71875 C 10.875 47.253906 11.183594 47.8125 11.71875 47.96875 C 12.253906 48.125 12.8125 47.816406 12.96875 47.28125 L 15.40625 39 L 34.53125 39 L 35 40.5625 C 33.816406 41.257813 33 42.535156 33 44 C 33 46.199219 34.800781 48 37 48 C 39.199219 48 41 46.199219 41 44 C 41 41.800781 39.199219 40 37 40 C 36.96875 40 36.9375 40 36.90625 40 L 34.1875 30.46875 C 39.457031 27.328125 43 21.570313 43 15 L 43 14 Z M 9.09375 16 L 40.90625 16 C 40.550781 21.640625 37.300781 26.5 32.625 29.0625 C 32.617188 29.066406 32.601563 29.058594 32.59375 29.0625 C 32.527344 29.097656 32.464844 29.140625 32.40625 29.1875 C 32.386719 29.199219 32.363281 29.207031 32.34375 29.21875 C 30.148438 30.363281 27.65625 31 25 31 C 22.378906 31 19.925781 30.367188 17.75 29.25 C 17.628906 29.128906 17.476563 29.042969 17.3125 29 C 12.675781 26.425781 9.445313 21.609375 9.09375 16 Z M 17.625 31.40625 C 19.878906 32.425781 22.367188 33 25 33 C 27.621094 33 30.097656 32.417969 32.34375 31.40625 L 33.96875 37 L 15.96875 37 Z M 36.8125 42 C 36.875 41.996094 36.9375 42 37 42 C 38.117188 42 39 42.882813 39 44 C 39 45.117188 38.117188 46 37 46 C 35.882813 46 35 45.117188 35 44 C 35 43.1875 35.472656 42.503906 36.15625 42.1875 C 36.375 42.207031 36.597656 42.152344 36.78125 42.03125 C 36.792969 42.03125 36.800781 42 36.8125 42 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89d4509 elementor-widget elementor-widget-heading\" data-id=\"89d4509\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Priv\u00e9 barbecue<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d8f7d2 e-con-full e-flex e-con e-child\" data-id=\"3d8f7d2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f024404 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f024404\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 9 4 C 6.2545455 4 4 6.2545455 4 9 L 4 41 C 4 43.745455 6.2545455 46 9 46 L 41 46 C 43.745455 46 46 43.745455 46 41 L 46 9 C 46 6.2545455 43.745455 4 41 4 L 9 4 z M 9 6 L 41 6 C 42.654545 6 44 7.3454545 44 9 L 44 41 C 44 42.654545 42.654545 44 41 44 L 9 44 C 7.3454545 44 6 42.654545 6 41 L 6 9 C 6 7.3454545 7.3454545 6 9 6 z M 17 14 L 17 36 L 21 36 L 21 28 L 29 28 C 32.309 28 35 25.309 35 22 L 35 20 C 35 16.691 32.309 14 29 14 L 21 14 L 19 14 L 17 14 z M 21 18 L 29 18 C 30.103 18 31 18.897 31 20 L 31 22 C 31 23.103 30.103 24 29 24 L 21 24 L 21 18 z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b1fbd4 elementor-widget elementor-widget-heading\" data-id=\"3b1fbd4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Priv\u00e9 parkeerplaats<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ae2cf0 e-flex e-con-boxed e-con e-child\" data-id=\"1ae2cf0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-22e2782 e-con-full e-flex e-con e-child\" data-id=\"22e2782\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ac4a350 elementor-widget elementor-widget-heading\" data-id=\"ac4a350\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A la carte opties<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9806739 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9806739\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69893d4 e-flex e-con-boxed e-con e-child\" data-id=\"69893d4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1cd1d42 e-con-full e-flex e-con e-child\" data-id=\"1cd1d42\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d320b4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4d320b4\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 24.935547 2.0351562 C 22.270282 2.0369964 19.62473 2.7230381 16.589844 4.0878906 A 1.0001 1.0001 0 0 0 16 5 L 16 8.6425781 C 14.758655 9.9293147 13.907185 10.961983 13.517578 11.611328 C 13.299814 11.974269 13.17264 12.255516 13.097656 12.480469 C 13.022672 12.705421 13 13 13 13 L 13 19 C 13 20.619611 13.792314 22.05148 14.996094 22.966797 L 12.007812 46.875 A 1.0001 1.0001 0 1 0 13.992188 47.125 L 16.898438 23.869141 C 17.2542 23.950225 17.620637 24 18 24 L 18.888672 24 L 17.005859 41.894531 A 1.0001 1.0001 0 1 0 18.994141 42.105469 L 20.900391 24 L 29.099609 24 L 31.005859 42.105469 A 1.0001 1.0001 0 1 0 32.994141 41.894531 L 31.111328 24 L 32 24 C 32.379363 24 32.7458 23.950225 33.101562 23.869141 L 36.007812 47.125 A 1.0001 1.0001 0 1 0 37.992188 46.875 L 35.003906 22.966797 C 36.207686 22.05148 37 20.619611 37 19 L 37 13 C 37 13 36.977334 12.705421 36.902344 12.480469 C 36.827364 12.255516 36.700186 11.974269 36.482422 11.611328 C 36.092819 10.961983 35.241345 9.9293147 34 8.6425781 L 34 5 A 1.0001 1.0001 0 0 0 33.402344 4.0839844 C 30.286024 2.7153444 27.600812 2.0333163 24.935547 2.0351562 z M 24.939453 3.9648438 C 27.102431 3.9640007 29.330693 4.5826375 32 5.7011719 L 32 9 A 1.0001 1.0001 0 0 0 32.292969 9.7070312 C 33.753685 11.167748 34.453107 12.114553 34.767578 12.638672 C 34.887253 12.838131 34.91626 12.921896 34.947266 13 L 15.052734 13 C 15.083742 12.921896 15.112749 12.838131 15.232422 12.638672 C 15.546893 12.114553 16.246315 11.167748 17.707031 9.7070312 A 1.0001 1.0001 0 0 0 18 9 L 18 5.6953125 C 20.592802 4.5842124 22.778367 3.965686 24.939453 3.9648438 z M 23 6 A 1.0001 1.0001 0 1 0 23 8 L 27 8 A 1.0001 1.0001 0 1 0 27 6 L 23 6 z M 15 15 L 24 15 L 24 22 L 20.162109 22 A 1.0001 1.0001 0 0 0 19.992188 21.986328 A 1.0001 1.0001 0 0 0 19.84375 22 L 18 22 C 16.331516 22 15 20.668484 15 19 L 15 15 z M 26 15 L 35 15 L 35 19 C 35 20.668484 33.668484 22 32 22 L 30.162109 22 A 1.0001 1.0001 0 0 0 29.978516 21.986328 A 1.0001 1.0001 0 0 0 29.841797 22 L 26 22 L 26 15 z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa8d0e9 elementor-widget elementor-widget-heading\" data-id=\"fa8d0e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Babystoel of kinderbed<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-136d538 elementor-widget elementor-widget-text-editor\" data-id=\"136d538\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t5 per week\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6608ca2 e-con-full e-flex e-con e-child\" data-id=\"6608ca2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b8c52c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7b8c52c\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 26.410156 4.078125 C 26.095062 4.0831924 25.779503 4.1025253 25.464844 4.1347656 C 24.625752 4.2207396 23.791489 4.4031919 22.978516 4.6855469 L 10.962891 8.8574219 A 1.0001 1.0001 0 0 0 10.949219 8.8632812 C 8.581384 9.7248553 7 11.98289 7 14.501953 L 7 15.308594 C 7 15.331364 7.015431 15.350307 7.015625 15.373047 L 4.4824219 16.640625 A 1.0001 1.0001 0 0 0 4.4707031 16.646484 C 0.22862996 18.842091 -1.3659578 24.229144 1.3359375 27.986328 L 11.197266 46.857422 C 12.430626 49.218501 15.666201 49.71719 17.552734 47.835938 L 27.414062 37.998047 A 1.0001 1.0001 0 0 0 27.416016 37.998047 C 27.512536 37.901527 27.62577 37.827022 27.751953 37.777344 L 44.007812 31.349609 C 47.621665 29.920825 50 26.422432 50 22.537109 C 50 19.369776 48.414538 16.409171 45.779297 14.652344 L 32.689453 5.9238281 C 30.810148 4.6709584 28.615814 4.0426535 26.410156 4.078125 z M 26.701172 6.0761719 C 27.044563 6.0805072 27.386437 6.1050462 27.726562 6.1484375 C 29.087066 6.3220026 30.407929 6.8064581 31.580078 7.5878906 L 44.669922 16.316406 C 46.75068 17.703579 48 20.036443 48 22.537109 C 48 25.607787 46.127632 28.361019 43.271484 29.490234 L 27.017578 35.917969 C 26.636764 36.068299 26.288837 36.295147 26 36.583984 L 16.140625 46.417969 C 15.169159 47.386716 13.605343 47.146561 12.970703 45.931641 L 3.0996094 27.039062 A 1.0001 1.0001 0 0 0 3.0136719 26.904297 C 0.97630631 24.183612 2.1093508 20.122146 5.390625 18.423828 L 7.5078125 17.363281 C 8.0044361 19.16488 8.9036254 20.829753 10.482422 21.910156 L 22.951172 30.441406 C 25.402753 32.119277 28.526473 32.478463 31.294922 31.402344 L 43.908203 26.501953 C 45.165901 26.013806 46 24.794533 46 23.445312 L 46 23.382812 C 46 21.073836 43.661306 19.41137 41.488281 20.189453 C 37.358038 21.668182 30.664063 24.058594 30.664062 24.058594 A 1.0001 1.0001 0 1 0 31.335938 25.941406 C 31.335938 25.941406 38.030353 23.551536 42.162109 22.072266 C 43.089084 21.740349 44 22.38379 44 23.382812 L 44 23.445312 C 44 23.976094 43.679849 24.444866 43.185547 24.636719 L 30.570312 29.539062 C 28.414762 30.376943 25.988497 30.097145 24.080078 28.791016 L 11.611328 20.259766 C 9.9756547 19.14044 9 17.290732 9 15.308594 L 9 14.501953 C 9 12.817975 10.048202 11.321286 11.630859 10.744141 C 11.630859 10.744141 11.632812 10.742188 11.632812 10.742188 L 23.634766 6.5742188 C 24.633055 6.2275012 25.670999 6.063166 26.701172 6.0761719 z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdd9af5 elementor-widget elementor-widget-heading\" data-id=\"fdd9af5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vellen kit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2137d9d elementor-widget elementor-widget-text-editor\" data-id=\"2137d9d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t8 \u20ac 90cm bed - 10 \u20ac 140cm bed\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd738b0 e-con-full e-flex e-con e-child\" data-id=\"bd738b0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7063ce elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a7063ce\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 11 0 C 8.832031 0 7.015625 0.546875 5.78125 1.78125 C 4.546875 3.015625 4 4.832031 4 7 L 4 8 L 1 8 C 0.96875 8 0.9375 8 0.90625 8 C 0.355469 8.027344 -0.0742188 8.496094 -0.046875 9.046875 C -0.0195313 9.597656 0.449219 10.027344 1 10 L 4 10 L 4 28.8125 C 3.972656 28.945313 3.972656 29.085938 4 29.21875 L 4 34.8125 C 3.972656 34.945313 3.972656 35.085938 4 35.21875 L 4 41 C 4 41.550781 4.449219 42 5 42 L 10 42 L 10 49 C 10 49.550781 10.449219 50 11 50 L 43 50 C 43.550781 50 44 49.550781 44 49 L 44 11.15625 C 44.003906 11.105469 44.003906 11.050781 44 11 L 44 10 L 49 10 C 49.359375 10.003906 49.695313 9.816406 49.878906 9.503906 C 50.058594 9.191406 50.058594 8.808594 49.878906 8.496094 C 49.695313 8.183594 49.359375 7.996094 49 8 L 44 8 L 44 7 C 44 4.9375 43.34375 3.152344 42.09375 1.90625 C 40.84375 0.660156 39.054688 0 37 0 Z M 11 2 L 37 2 C 38.640625 2 39.859375 2.488281 40.6875 3.3125 C 41.136719 3.761719 41.460938 4.347656 41.6875 5.03125 C 40.816406 4.367188 39.855469 4 39 4 C 37.992188 4 36.644531 4.273438 35.625 5.375 C 34.605469 6.476563 34 8.253906 34 11 L 34 26.09375 C 33.09375 26.289063 32.304688 26.722656 31.5625 27.09375 C 30.5625 27.59375 29.667969 28 29 28 C 28.332031 28 27.4375 27.59375 26.4375 27.09375 C 25.4375 26.59375 24.332031 26 23 26 C 21.667969 26 20.5625 26.59375 19.5625 27.09375 C 18.5625 27.59375 17.667969 28 17 28 C 16.332031 28 15.4375 27.59375 14.4375 27.09375 C 13.4375 26.59375 12.332031 26 11 26 C 9.667969 26 8.5625 26.59375 7.5625 27.09375 C 7 27.375 6.476563 27.644531 6 27.8125 L 6 9.1875 C 6.027344 9.054688 6.027344 8.914063 6 8.78125 L 6 7 C 6 5.167969 6.453125 3.984375 7.21875 3.21875 C 7.984375 2.453125 9.167969 2 11 2 Z M 39 6 C 39.617188 6 40.292969 6.179688 40.875 6.84375 C 41.113281 7.117188 41.339844 7.503906 41.53125 8 L 36.40625 8 C 36.601563 7.40625 36.839844 6.992188 37.09375 6.71875 C 37.648438 6.121094 38.3125 6 39 6 Z M 36.03125 10 L 41.9375 10 C 41.964844 10.308594 42 10.640625 42 11 C 42 11.03125 42 11.0625 42 11.09375 L 42 48 L 12 48 L 12 42 L 35 42 C 35.550781 42 36 41.550781 36 41 L 36 33.1875 C 36.027344 33.054688 36.027344 32.914063 36 32.78125 L 36 27.1875 C 36.027344 27.054688 36.027344 26.914063 36 26.78125 L 36 11 C 36 10.644531 36.011719 10.308594 36.03125 10 Z M 11 28 C 11.667969 28 12.5625 28.40625 13.5625 28.90625 C 14.5625 29.40625 15.667969 30 17 30 C 18.332031 30 19.4375 29.40625 20.4375 28.90625 C 21.4375 28.40625 22.332031 28 23 28 C 23.667969 28 24.5625 28.40625 25.5625 28.90625 C 26.5625 29.40625 27.667969 30 29 30 C 30.332031 30 31.4375 29.40625 32.4375 28.90625 C 33 28.625 33.523438 28.355469 34 28.1875 L 34 32.09375 C 33.09375 32.289063 32.304688 32.722656 31.5625 33.09375 C 30.5625 33.59375 29.667969 34 29 34 C 28.332031 34 27.4375 33.59375 26.4375 33.09375 C 25.4375 32.59375 24.332031 32 23 32 C 21.667969 32 20.5625 32.59375 19.5625 33.09375 C 18.5625 33.59375 17.667969 34 17 34 C 16.332031 34 15.4375 33.59375 14.4375 33.09375 C 13.4375 32.59375 12.332031 32 11 32 C 9.667969 32 8.5625 32.59375 7.5625 33.09375 C 7 33.375 6.476563 33.644531 6 33.8125 L 6 29.90625 C 6.90625 29.710938 7.695313 29.277344 8.4375 28.90625 C 9.4375 28.40625 10.332031 28 11 28 Z M 11 34 C 11.667969 34 12.5625 34.40625 13.5625 34.90625 C 14.5625 35.40625 15.667969 36 17 36 C 18.332031 36 19.4375 35.40625 20.4375 34.90625 C 21.4375 34.40625 22.332031 34 23 34 C 23.667969 34 24.5625 34.40625 25.5625 34.90625 C 26.5625 35.40625 27.667969 36 29 36 C 30.332031 36 31.4375 35.40625 32.4375 34.90625 C 33 34.625 33.523438 34.355469 34 34.1875 L 34 40 L 6 40 L 6 35.90625 C 6.90625 35.710938 7.695313 35.277344 8.4375 34.90625 C 9.4375 34.40625 10.332031 34 11 34 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0f82ba elementor-widget elementor-widget-heading\" data-id=\"f0f82ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Handdoekpakket<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e072dba elementor-widget elementor-widget-text-editor\" data-id=\"e072dba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t5 \u20ac per persoon\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59a58bb e-con-full e-flex e-con e-child\" data-id=\"59a58bb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-026b030 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"026b030\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 47.3125 0.0625 C 46.40625 0.125 45.570313 0.707031 45.28125 1.65625 L 45.28125 1.6875 C 45.273438 1.710938 45.265625 1.734375 45.25 1.75 L 34.125 30.65625 C 32.109375 31.519531 29.292969 32.976563 26.84375 35.03125 C 24.234375 37.21875 22 40.113281 22 43.6875 C 22 45.21875 22.566406 46.859375 23.875 48.0625 C 25.183594 49.265625 27.179688 50 29.90625 50 L 49 50 C 49.5 49.984375 49.910156 49.605469 49.964844 49.109375 C 50.019531 48.613281 49.703125 48.15625 49.21875 48.03125 C 49.21875 48.03125 45.65625 47.207031 42.75 44.9375 C 41.296875 43.804688 40.03125 42.339844 39.40625 40.46875 C 38.78125 38.597656 38.753906 36.285156 39.9375 33.28125 C 39.9375 33.261719 39.9375 33.238281 39.9375 33.21875 L 49.8125 3.28125 L 49.84375 3.21875 L 49.8125 3.21875 C 50.289063 2.007813 49.636719 0.675781 48.375 0.25 L 48.40625 0.1875 C 48.375 0.175781 48.34375 0.199219 48.3125 0.1875 C 48.28125 0.179688 48.28125 0.132813 48.25 0.125 L 48.21875 0.1875 C 47.917969 0.0898438 47.613281 0.0429688 47.3125 0.0625 Z M 47.59375 2.03125 C 47.644531 2.046875 47.695313 2.054688 47.75 2.0625 C 47.941406 2.109375 48.019531 2.382813 47.96875 2.5 C 47.957031 2.53125 47.945313 2.5625 47.9375 2.59375 L 38.375 31.625 L 36.1875 30.8125 L 47.125 2.34375 C 47.136719 2.3125 47.148438 2.28125 47.15625 2.25 C 47.203125 2.058594 47.476563 1.980469 47.59375 2.03125 Z M 16.09375 4.09375 C 12.992188 4.09375 10.199219 5.710938 8.5 8.3125 C 7.898438 8.3125 7.5 8.394531 7 8.59375 L 8.40625 10.1875 C 8.707031 10.085938 8.886719 10.101563 9.1875 10 L 9.6875 10 L 9.90625 9.59375 C 11.105469 7.394531 13.5 6 16 6 C 19.199219 6 22.011719 8.210938 22.8125 11.3125 L 23 12.09375 L 24 12.09375 C 25.898438 12.09375 27.40625 13.394531 27.90625 15.09375 L 30 15.09375 C 29.5 12.394531 27.292969 10.292969 24.59375 10.09375 C 23.292969 6.492188 19.992188 4.09375 16.09375 4.09375 Z M 1.90625 5.96875 C 1.863281 5.976563 1.820313 5.988281 1.78125 6 C 1.4375 6.070313 1.152344 6.320313 1.039063 6.652344 C 0.921875 6.984375 0.992188 7.355469 1.21875 7.625 L 3.9375 10.9375 C 2.980469 12.082031 2.304688 13.457031 2.09375 15 L 4.09375 15 C 4.269531 14.054688 4.652344 13.179688 5.1875 12.4375 L 8.125 16 L 1 16 C 0.699219 16 0.386719 16.113281 0.1875 16.3125 C -0.0117188 16.613281 0 16.886719 0 17.1875 L 5 49.1875 C 5.101563 49.585938 5.5 50 6 50 L 25 50 C 23.898438 49.5 23.101563 48.800781 22.5 48 L 6.90625 48 L 2.1875 18 L 9.75 18 L 14.125 23.3125 C 14.039063 23.523438 14 23.75 14 24 C 14 25.101563 14.898438 26 16 26 C 17.101563 26 18 25.101563 18 24 C 18 22.898438 17.101563 22 16 22 C 15.894531 22 15.789063 22.011719 15.6875 22.03125 L 2.78125 6.375 C 2.761719 6.351563 2.742188 6.332031 2.71875 6.3125 C 2.699219 6.28125 2.679688 6.25 2.65625 6.21875 C 2.597656 6.179688 2.535156 6.148438 2.46875 6.125 C 2.449219 6.101563 2.429688 6.082031 2.40625 6.0625 C 2.347656 6.035156 2.28125 6.015625 2.21875 6 C 2.117188 5.972656 2.011719 5.960938 1.90625 5.96875 Z M 13.09375 16 L 14.6875 18 L 29.8125 18 L 27.40625 33.3125 C 28.207031 32.710938 28.886719 32.210938 29.6875 31.8125 L 32 17.1875 C 32 16.886719 32.011719 16.605469 31.8125 16.40625 C 31.613281 16.105469 31.300781 16 31 16 Z M 34.9375 32.46875 L 37.71875 33.5 C 36.757813 36.429688 36.796875 38.988281 37.5 41.09375 C 38.28125 43.433594 39.828125 45.195313 41.5 46.5 C 42.425781 47.222656 43.300781 47.527344 44.21875 48 L 39.34375 48 C 36.863281 47.679688 35.75 46.753906 35.1875 45.75 C 34.625 44.746094 34.625 43.519531 34.875 42.5625 C 34.96875 42.246094 34.902344 41.90625 34.695313 41.652344 C 34.488281 41.394531 34.171875 41.257813 33.84375 41.28125 C 33.402344 41.3125 33.035156 41.628906 32.9375 42.0625 C 32.585938 43.40625 32.546875 45.15625 33.4375 46.75 C 33.6875 47.203125 34.03125 47.613281 34.4375 48 L 33.8125 48 C 31.785156 48 30.578125 47.535156 29.90625 46.96875 C 29.234375 46.402344 28.949219 45.6875 28.9375 44.75 C 28.917969 42.871094 30.265625 40.308594 31.53125 39 C 31.839844 38.707031 31.925781 38.25 31.75 37.863281 C 31.574219 37.476563 31.171875 37.242188 30.75 37.28125 C 30.5 37.300781 30.265625 37.410156 30.09375 37.59375 C 28.457031 39.285156 26.90625 42.058594 26.9375 44.78125 C 26.949219 45.847656 27.269531 46.949219 27.96875 47.84375 C 26.695313 47.613281 25.820313 47.144531 25.21875 46.59375 C 24.355469 45.796875 24 44.757813 24 43.6875 C 24 40.960938 25.757813 38.550781 28.125 36.5625 C 30.363281 34.683594 33.0625 33.269531 34.9375 32.46875 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e144fa8 elementor-widget elementor-widget-heading\" data-id=\"e144fa8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Schoonmaak aan het einde van het verblijf<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6294ab1 elementor-widget elementor-widget-text-editor\" data-id=\"6294ab1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t70 per week - \u20ac40 kort verblijf\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-404d96e e-con-full e-flex e-con e-child\" data-id=\"404d96e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53fe99a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"53fe99a\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 11 0 C 9.897 0 9 0.897 9 2 L 9 19 C 9 20.103 9.897 21 11 21 L 13.546875 21 C 13.341875 20.357 13.197422 19.687 13.107422 19 L 11 19 L 11 2 L 38 2 L 38.001953 18.865234 C 38.499953 19.354234 38.945984 19.894516 39.333984 20.478516 C 39.739984 20.111516 40 19.588 40 19 L 40 2 C 40 0.897 39.103 0 38 0 L 11 0 z M 24.5 6 C 23.083334 6 21.893559 6.5672556 21.126953 7.4296875 C 20.360347 8.2921194 20 9.4027779 20 10.5 C 20 11.597222 20.360347 12.707881 21.126953 13.570312 C 21.893559 14.432745 23.083334 15 24.5 15 C 25.916666 15 27.106441 14.432744 27.873047 13.570312 C 28.639653 12.707882 29 11.597222 29 10.5 C 29 9.4027779 28.639653 8.2921194 27.873047 7.4296875 C 27.106441 6.5672556 25.916666 6 24.5 6 z M 24.5 8 C 25.416666 8 25.976893 8.3077444 26.376953 8.7578125 C 26.777013 9.2078806 27 9.8472221 27 10.5 C 27 11.152778 26.777013 11.792119 26.376953 12.242188 C 25.976893 12.692255 25.416666 13 24.5 13 C 23.583334 13 23.023107 12.692256 22.623047 12.242188 C 22.222987 11.792118 22 11.152778 22 10.5 C 22 9.8472221 22.222987 9.2078806 22.623047 8.7578125 C 23.023107 8.3077444 23.583334 8 24.5 8 z M 18.005859 10.587891 C 16.160859 12.321891 15 14.775 15 17.5 C 15 19.268594 15.491906 20.920303 16.337891 22.337891 C 14.89163 23.784151 14 25.785043 14 28 C 14 30.969534 15.607931 33.547305 18 34.927734 L 18 47 A 1.0001 1.0001 0 0 0 18.292969 47.707031 L 20.292969 49.707031 A 1.0001 1.0001 0 0 0 21 50 L 23 50 A 1.0001 1.0001 0 0 0 23.707031 49.707031 L 25.707031 47.707031 A 1.0001 1.0001 0 0 0 26 47 L 26 45 A 1.0001 1.0001 0 0 0 25.707031 44.292969 L 24.914062 43.5 L 25.707031 42.707031 A 1.0001 1.0001 0 0 0 26 42 L 26 40 A 1.0001 1.0001 0 0 0 25.832031 39.445312 L 25.201172 38.5 L 25.832031 37.554688 A 1.0001 1.0001 0 0 0 26 37 L 26 34.927734 C 26.722771 34.510633 27.371339 33.983333 27.927734 33.369141 C 29.622602 34.082594 31.505554 34.181908 33.251953 33.666016 L 41.292969 41.707031 A 1.0001 1.0001 0 0 0 42 42 L 45 42 A 1.0001 1.0001 0 0 0 45.707031 41.707031 L 46.707031 40.707031 A 1.0001 1.0001 0 0 0 47 40 L 47 37 A 1.0001 1.0001 0 0 0 46.707031 36.292969 L 45.707031 35.292969 A 1.0001 1.0001 0 0 0 45 35 L 44 35 L 44 34 A 1.0001 1.0001 0 0 0 43.707031 33.292969 L 41.707031 31.292969 A 1.0001 1.0001 0 0 0 41 31 L 40 31 L 40 30 A 1.0001 1.0001 0 0 0 39.707031 29.292969 L 38.664062 28.25 C 39.460018 25.541608 38.787727 22.498664 36.644531 20.355469 C 35.844267 19.555204 34.918457 18.962623 33.931641 18.572266 C 33.972627 18.219938 34 17.863371 34 17.5 C 34 14.775 32.840094 12.321891 30.996094 10.587891 C 30.985094 11.446891 30.810094 12.265672 30.496094 13.013672 C 31.436094 14.266672 32 15.816 32 17.5 C 32 17.695423 31.989682 17.888493 31.974609 18.080078 C 31.650595 18.040227 31.325944 18.011719 31 18.011719 C 28.959343 18.011719 26.918263 18.792675 25.355469 20.355469 C 25.267716 20.443221 25.191617 20.533451 25.111328 20.623047 C 24.155797 20.221251 23.104412 20 22 20 C 20.516313 20 19.134273 20.408302 17.945312 21.107422 C 17.350995 20.035513 17 18.811378 17 17.5 C 17 15.816 17.564859 14.266672 18.505859 13.013672 C 18.191859 12.265672 18.016859 11.446891 18.005859 10.587891 z M 31 19.988281 C 31.186858 19.988281 31.374291 19.997716 31.560547 20.015625 C 31.559167 20.019484 31.558027 20.023488 31.556641 20.027344 C 31.809001 20.047805 32.059455 20.094495 32.308594 20.142578 C 33.37051 20.386364 34.385522 20.924585 35.230469 21.769531 C 37.606881 24.145944 37.606881 27.854056 35.230469 30.230469 C 33.545913 31.915025 31.209851 32.312819 29.136719 31.609375 C 29.68448 30.524908 30 29.30172 30 28 C 30 27.693934 29.980455 27.392666 29.947266 27.095703 C 29.943342 27.061669 29.937953 27.028028 29.933594 26.994141 C 29.956175 26.994894 29.977234 27 30 27 C 31.105 27 32 26.105 32 25 C 32 23.895 31.105 23 30 23 C 29.47556 23 29.003089 23.20714 28.646484 23.537109 C 28.168128 22.82453 27.573547 22.200068 26.896484 21.675781 C 28.066399 20.563474 29.528784 19.988281 31 19.988281 z M 22 22 C 22.986731 22 23.906356 22.231291 24.71875 22.634766 L 24.90625 22.736328 C 25.832335 23.242594 26.606521 23.981529 27.148438 24.882812 C 27.150671 24.886556 27.152071 24.890782 27.154297 24.894531 C 27.414094 25.328785 27.618033 25.801875 27.761719 26.302734 C 27.774845 26.348937 27.784809 26.396672 27.796875 26.443359 C 27.847217 26.636295 27.886492 26.834369 27.917969 27.035156 C 27.928775 27.104819 27.94074 27.173624 27.949219 27.244141 C 27.979333 27.49187 28 27.742531 28 28 C 28 28.30816 27.971137 28.60692 27.927734 28.900391 C 27.921231 28.945456 27.915665 28.990454 27.908203 29.035156 C 27.748803 29.967016 27.382047 30.818326 26.851562 31.546875 L 26.595703 31.898438 C 25.504331 33.191011 23.866667 34 22 34 C 18.629915 34 16 31.370085 16 28 C 16 26.42078 16.582437 25.008927 17.542969 23.949219 C 18.253621 24.713085 19.089201 25.357245 20.015625 25.855469 C 20.012074 25.904207 20 25.950351 20 26 C 20 27.105 20.895 28 22 28 C 23.105 28 24 27.105 24 26 C 24 24.895 23.105 24 22 24 C 21.699117 24 21.41607 24.070566 21.160156 24.189453 C 20.399853 23.808653 19.707712 23.314644 19.121094 22.710938 C 19.970764 22.256751 20.949068 22 22 22 z M 37.783203 30.197266 L 38 30.414062 L 38 32 A 1.0001 1.0001 0 0 0 39 33 L 40.585938 33 L 42 34.414062 L 42 36 A 1.0001 1.0001 0 0 0 43 37 L 44.585938 37 L 45 37.414062 L 45 39.585938 L 44.585938 40 L 42.414062 40 L 35.201172 32.787109 C 35.713149 32.468077 36.198909 32.090154 36.644531 31.644531 C 37.090537 31.198525 37.464483 30.710035 37.783203 30.197266 z M 20 35.738281 C 20.640198 35.902454 21.30741 36 22 36 C 22.69259 36 23.359802 35.902454 24 35.738281 L 24 36.697266 L 23.167969 37.945312 A 1.0001 1.0001 0 0 0 23.167969 39.054688 L 24 40.302734 L 24 41.585938 L 22.792969 42.792969 A 1.0001 1.0001 0 0 0 22.792969 44.207031 L 24 45.414062 L 24 46.585938 L 22.585938 48 L 21.414062 48 L 20 46.585938 L 20 35.738281 z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97e4895 elementor-widget elementor-widget-heading\" data-id=\"97e4895\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Late aankomst<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c4794a elementor-widget elementor-widget-text-editor\" data-id=\"5c4794a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Op aanvraag bij de receptie<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a3759d e-con-full e-flex e-con e-child\" data-id=\"9a3759d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f5f8d5 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2f5f8d5\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 11 0 C 9.897 0 9 0.897 9 2 L 9 19 C 9 20.103 9.897 21 11 21 L 13.546875 21 C 13.341875 20.357 13.197422 19.687 13.107422 19 L 11 19 L 11 2 L 38 2 L 38.001953 18.865234 C 38.499953 19.354234 38.945984 19.894516 39.333984 20.478516 C 39.739984 20.111516 40 19.588 40 19 L 40 2 C 40 0.897 39.103 0 38 0 L 11 0 z M 24.5 6 C 23.083334 6 21.893559 6.5672556 21.126953 7.4296875 C 20.360347 8.2921194 20 9.4027779 20 10.5 C 20 11.597222 20.360347 12.707881 21.126953 13.570312 C 21.893559 14.432745 23.083334 15 24.5 15 C 25.916666 15 27.106441 14.432744 27.873047 13.570312 C 28.639653 12.707882 29 11.597222 29 10.5 C 29 9.4027779 28.639653 8.2921194 27.873047 7.4296875 C 27.106441 6.5672556 25.916666 6 24.5 6 z M 24.5 8 C 25.416666 8 25.976893 8.3077444 26.376953 8.7578125 C 26.777013 9.2078806 27 9.8472221 27 10.5 C 27 11.152778 26.777013 11.792119 26.376953 12.242188 C 25.976893 12.692255 25.416666 13 24.5 13 C 23.583334 13 23.023107 12.692256 22.623047 12.242188 C 22.222987 11.792118 22 11.152778 22 10.5 C 22 9.8472221 22.222987 9.2078806 22.623047 8.7578125 C 23.023107 8.3077444 23.583334 8 24.5 8 z M 18.005859 10.587891 C 16.160859 12.321891 15 14.775 15 17.5 C 15 19.268594 15.491906 20.920303 16.337891 22.337891 C 14.89163 23.784151 14 25.785043 14 28 C 14 30.969534 15.607931 33.547305 18 34.927734 L 18 47 A 1.0001 1.0001 0 0 0 18.292969 47.707031 L 20.292969 49.707031 A 1.0001 1.0001 0 0 0 21 50 L 23 50 A 1.0001 1.0001 0 0 0 23.707031 49.707031 L 25.707031 47.707031 A 1.0001 1.0001 0 0 0 26 47 L 26 45 A 1.0001 1.0001 0 0 0 25.707031 44.292969 L 24.914062 43.5 L 25.707031 42.707031 A 1.0001 1.0001 0 0 0 26 42 L 26 40 A 1.0001 1.0001 0 0 0 25.832031 39.445312 L 25.201172 38.5 L 25.832031 37.554688 A 1.0001 1.0001 0 0 0 26 37 L 26 34.927734 C 26.722771 34.510633 27.371339 33.983333 27.927734 33.369141 C 29.622602 34.082594 31.505554 34.181908 33.251953 33.666016 L 41.292969 41.707031 A 1.0001 1.0001 0 0 0 42 42 L 45 42 A 1.0001 1.0001 0 0 0 45.707031 41.707031 L 46.707031 40.707031 A 1.0001 1.0001 0 0 0 47 40 L 47 37 A 1.0001 1.0001 0 0 0 46.707031 36.292969 L 45.707031 35.292969 A 1.0001 1.0001 0 0 0 45 35 L 44 35 L 44 34 A 1.0001 1.0001 0 0 0 43.707031 33.292969 L 41.707031 31.292969 A 1.0001 1.0001 0 0 0 41 31 L 40 31 L 40 30 A 1.0001 1.0001 0 0 0 39.707031 29.292969 L 38.664062 28.25 C 39.460018 25.541608 38.787727 22.498664 36.644531 20.355469 C 35.844267 19.555204 34.918457 18.962623 33.931641 18.572266 C 33.972627 18.219938 34 17.863371 34 17.5 C 34 14.775 32.840094 12.321891 30.996094 10.587891 C 30.985094 11.446891 30.810094 12.265672 30.496094 13.013672 C 31.436094 14.266672 32 15.816 32 17.5 C 32 17.695423 31.989682 17.888493 31.974609 18.080078 C 31.650595 18.040227 31.325944 18.011719 31 18.011719 C 28.959343 18.011719 26.918263 18.792675 25.355469 20.355469 C 25.267716 20.443221 25.191617 20.533451 25.111328 20.623047 C 24.155797 20.221251 23.104412 20 22 20 C 20.516313 20 19.134273 20.408302 17.945312 21.107422 C 17.350995 20.035513 17 18.811378 17 17.5 C 17 15.816 17.564859 14.266672 18.505859 13.013672 C 18.191859 12.265672 18.016859 11.446891 18.005859 10.587891 z M 31 19.988281 C 31.186858 19.988281 31.374291 19.997716 31.560547 20.015625 C 31.559167 20.019484 31.558027 20.023488 31.556641 20.027344 C 31.809001 20.047805 32.059455 20.094495 32.308594 20.142578 C 33.37051 20.386364 34.385522 20.924585 35.230469 21.769531 C 37.606881 24.145944 37.606881 27.854056 35.230469 30.230469 C 33.545913 31.915025 31.209851 32.312819 29.136719 31.609375 C 29.68448 30.524908 30 29.30172 30 28 C 30 27.693934 29.980455 27.392666 29.947266 27.095703 C 29.943342 27.061669 29.937953 27.028028 29.933594 26.994141 C 29.956175 26.994894 29.977234 27 30 27 C 31.105 27 32 26.105 32 25 C 32 23.895 31.105 23 30 23 C 29.47556 23 29.003089 23.20714 28.646484 23.537109 C 28.168128 22.82453 27.573547 22.200068 26.896484 21.675781 C 28.066399 20.563474 29.528784 19.988281 31 19.988281 z M 22 22 C 22.986731 22 23.906356 22.231291 24.71875 22.634766 L 24.90625 22.736328 C 25.832335 23.242594 26.606521 23.981529 27.148438 24.882812 C 27.150671 24.886556 27.152071 24.890782 27.154297 24.894531 C 27.414094 25.328785 27.618033 25.801875 27.761719 26.302734 C 27.774845 26.348937 27.784809 26.396672 27.796875 26.443359 C 27.847217 26.636295 27.886492 26.834369 27.917969 27.035156 C 27.928775 27.104819 27.94074 27.173624 27.949219 27.244141 C 27.979333 27.49187 28 27.742531 28 28 C 28 28.30816 27.971137 28.60692 27.927734 28.900391 C 27.921231 28.945456 27.915665 28.990454 27.908203 29.035156 C 27.748803 29.967016 27.382047 30.818326 26.851562 31.546875 L 26.595703 31.898438 C 25.504331 33.191011 23.866667 34 22 34 C 18.629915 34 16 31.370085 16 28 C 16 26.42078 16.582437 25.008927 17.542969 23.949219 C 18.253621 24.713085 19.089201 25.357245 20.015625 25.855469 C 20.012074 25.904207 20 25.950351 20 26 C 20 27.105 20.895 28 22 28 C 23.105 28 24 27.105 24 26 C 24 24.895 23.105 24 22 24 C 21.699117 24 21.41607 24.070566 21.160156 24.189453 C 20.399853 23.808653 19.707712 23.314644 19.121094 22.710938 C 19.970764 22.256751 20.949068 22 22 22 z M 37.783203 30.197266 L 38 30.414062 L 38 32 A 1.0001 1.0001 0 0 0 39 33 L 40.585938 33 L 42 34.414062 L 42 36 A 1.0001 1.0001 0 0 0 43 37 L 44.585938 37 L 45 37.414062 L 45 39.585938 L 44.585938 40 L 42.414062 40 L 35.201172 32.787109 C 35.713149 32.468077 36.198909 32.090154 36.644531 31.644531 C 37.090537 31.198525 37.464483 30.710035 37.783203 30.197266 z M 20 35.738281 C 20.640198 35.902454 21.30741 36 22 36 C 22.69259 36 23.359802 35.902454 24 35.738281 L 24 36.697266 L 23.167969 37.945312 A 1.0001 1.0001 0 0 0 23.167969 39.054688 L 24 40.302734 L 24 41.585938 L 22.792969 42.792969 A 1.0001 1.0001 0 0 0 22.792969 44.207031 L 24 45.414062 L 24 46.585938 L 22.585938 48 L 21.414062 48 L 20 46.585938 L 20 35.738281 z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-838609a elementor-widget elementor-widget-heading\" data-id=\"838609a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Late start<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a371dab elementor-widget elementor-widget-text-editor\" data-id=\"a371dab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>30 \u20ac ( op basis van beschikbaarheid 7 dagen voor uw verblijf )<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b0a0d3 e-con-full e-flex e-con e-child\" data-id=\"0b0a0d3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06ff755 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"06ff755\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 14 2 C 6.28125 2 0 8.28125 0 16 C 0 19.859375 1.558594 23.371094 4.09375 25.90625 C 4.113281 25.917969 4.136719 25.929688 4.15625 25.9375 C 4.183594 25.964844 4.191406 26.007813 4.21875 26.03125 C 4.285156 26.113281 4.40625 26.269531 4.625 26.71875 C 4.929688 27.34375 5.304688 28.363281 5.5 29.84375 C 5.570313 30.375 5.46875 32.316406 5.21875 34.375 C 4.96875 36.433594 4.605469 38.726563 4.25 40.4375 C 3.929688 41.972656 3.960938 43.375 4.59375 44.5625 C 5.226563 45.75 6.417969 46.59375 8 47.0625 C 8.042969 47.066406 8.082031 47.066406 8.125 47.0625 L 13.0625 47.90625 C 13.074219 47.90625 13.082031 47.90625 13.09375 47.90625 C 13.382813 47.941406 14.25 48.007813 15.1875 47.90625 C 15.65625 47.855469 16.144531 47.789063 16.625 47.5625 C 17.105469 47.335938 17.628906 46.914063 17.84375 46.28125 C 18.082031 45.574219 17.949219 44.824219 17.71875 44.3125 C 17.488281 43.800781 17.242188 43.460938 17.03125 43.0625 C 16.609375 42.265625 16.210938 41.242188 16.8125 38.65625 C 17.332031 36.425781 17.898438 34.664063 18.5625 32.5 C 19.117188 30.691406 19.882813 29.726563 20.46875 29.1875 C 21.054688 28.648438 21.34375 28.59375 21.34375 28.59375 C 21.441406 28.566406 21.539063 28.523438 21.625 28.46875 L 38.25 24.34375 C 38.691406 24.230469 39 23.832031 39 23.375 L 39 8.625 C 39 8.167969 38.691406 7.769531 38.25 7.65625 L 18.28125 2.6875 L 18.21875 2.65625 L 18.21875 2.6875 C 16.886719 2.265625 15.476563 2 14 2 Z M 14 4 C 15.28125 4 16.527344 4.21875 17.6875 4.59375 C 17.707031 4.59375 17.730469 4.59375 17.75 4.59375 L 37 9.40625 L 37 22.59375 L 17.75 27.40625 C 17.730469 27.40625 17.707031 27.40625 17.6875 27.40625 C 16.527344 27.78125 15.28125 28 14 28 C 10.722656 28 7.757813 26.6875 5.59375 24.5625 C 5.5625 24.539063 5.53125 24.519531 5.5 24.5 C 5.480469 24.480469 5.457031 24.457031 5.4375 24.4375 C 5.417969 24.414063 5.398438 24.394531 5.375 24.375 C 3.277344 22.214844 2 19.253906 2 16 C 2 9.363281 7.363281 4 14 4 Z M 14 9 C 10.144531 9 7 12.144531 7 16 C 7 19.855469 10.144531 23 14 23 C 17.855469 23 21 19.855469 21 16 C 21 12.144531 17.855469 9 14 9 Z M 40.78125 9.96875 C 40.253906 10.074219 39.890625 10.5625 39.945313 11.101563 C 40.003906 11.636719 40.460938 12.039063 41 12.03125 C 43.320313 12.03125 43.691406 12.378906 44.46875 12.875 C 45.246094 13.371094 46.433594 14.03125 49 14.03125 C 49.402344 14.085938 49.800781 13.902344 50.019531 13.5625 C 50.238281 13.21875 50.238281 12.78125 50.019531 12.4375 C 49.800781 12.097656 49.402344 11.914063 49 11.96875 C 46.71875 11.96875 46.375 11.628906 45.59375 11.125 C 44.8125 10.621094 43.601563 9.96875 41 9.96875 C 40.925781 9.960938 40.855469 9.960938 40.78125 9.96875 Z M 14 11 C 16.773438 11 19 13.226563 19 16 C 19 18.773438 16.773438 21 14 21 C 11.226563 21 9 18.773438 9 16 C 9 13.226563 11.226563 11 14 11 Z M 40.78125 14.96875 C 40.253906 15.074219 39.890625 15.5625 39.945313 16.101563 C 40.003906 16.636719 40.460938 17.039063 41 17.03125 C 43.320313 17.03125 43.691406 17.378906 44.46875 17.875 C 45.246094 18.371094 46.433594 19.03125 49 19.03125 C 49.402344 19.085938 49.800781 18.902344 50.019531 18.5625 C 50.238281 18.21875 50.238281 17.78125 50.019531 17.4375 C 49.800781 17.097656 49.402344 16.914063 49 16.96875 C 46.71875 16.96875 46.375 16.628906 45.59375 16.125 C 44.8125 15.621094 43.601563 14.96875 41 14.96875 C 40.925781 14.960938 40.855469 14.960938 40.78125 14.96875 Z M 40.78125 19.96875 C 40.253906 20.074219 39.890625 20.5625 39.945313 21.101563 C 40.003906 21.636719 40.460938 22.039063 41 22.03125 C 43.320313 22.03125 43.691406 22.378906 44.46875 22.875 C 45.246094 23.371094 46.433594 24.03125 49 24.03125 C 49.402344 24.085938 49.800781 23.902344 50.019531 23.5625 C 50.238281 23.21875 50.238281 22.78125 50.019531 22.4375 C 49.800781 22.097656 49.402344 21.914063 49 21.96875 C 46.71875 21.96875 46.375 21.628906 45.59375 21.125 C 44.8125 20.621094 43.601563 19.96875 41 19.96875 C 40.925781 19.960938 40.855469 19.960938 40.78125 19.96875 Z M 7.25 28.25 C 9.257813 29.363281 11.546875 30 14 30 C 15.304688 30 16.554688 29.777344 17.75 29.4375 C 17.351563 30.109375 16.960938 30.9375 16.65625 31.9375 C 15.996094 34.09375 15.414063 35.878906 14.875 38.1875 C 14.195313 41.109375 14.667969 42.902344 15.25 44 C 15.542969 44.550781 15.804688 44.902344 15.90625 45.125 C 16.007813 45.347656 16.03125 45.351563 15.9375 45.625 C 15.9375 45.621094 15.949219 45.671875 15.78125 45.75 C 15.613281 45.828125 15.300781 45.902344 14.96875 45.9375 C 14.316406 46.007813 13.589844 45.929688 13.375 45.90625 L 13.34375 45.90625 L 8.5625 45.125 C 8.546875 45.121094 8.546875 45.097656 8.53125 45.09375 C 7.300781 44.71875 6.667969 44.238281 6.34375 43.625 C 6.015625 43.003906 5.953125 42.121094 6.21875 40.84375 C 6.59375 39.054688 6.960938 36.710938 7.21875 34.59375 C 7.476563 32.476563 7.648438 30.722656 7.5 29.59375 C 7.4375 29.105469 7.34375 28.664063 7.25 28.25 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ddad3c elementor-widget elementor-widget-heading\" data-id=\"5ddad3c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Haardroger<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a30d019 elementor-widget elementor-widget-text-editor\" data-id=\"a30d019\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tOp aanvraag bij de receptie\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a8bd4d e-con-full e-flex e-con e-child\" data-id=\"4a8bd4d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3959979 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3959979\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 0.8125 9 C 0.335938 9.089844 -0.0078125 9.511719 0 10 L 0 40 C 0 40.550781 0.449219 41 1 41 L 1.28125 41 L 2.0625 43.3125 C 2.195313 43.71875 2.574219 43.996094 3 44 L 6 44 C 6.425781 43.996094 6.804688 43.71875 6.9375 43.3125 L 7.71875 41 L 42.28125 41 L 43.0625 43.3125 C 43.195313 43.71875 43.574219 43.996094 44 44 L 47 44 C 47.425781 43.996094 47.804688 43.71875 47.9375 43.3125 L 48.71875 41 L 49 41 C 49.550781 41 50 40.550781 50 40 L 50 10 C 50 9.449219 49.550781 9 49 9 L 1 9 C 0.96875 9 0.9375 9 0.90625 9 C 0.875 9 0.84375 9 0.8125 9 Z M 2 11 L 48 11 L 48 39 L 2 39 Z M 4.8125 13 C 4.335938 13.089844 3.992188 13.511719 4 14 L 4 36 C 4 36.550781 4.449219 37 5 37 L 39 37 C 39.550781 37 40 36.550781 40 36 L 40 14 C 40 13.449219 39.550781 13 39 13 L 5 13 C 4.96875 13 4.9375 13 4.90625 13 C 4.875 13 4.84375 13 4.8125 13 Z M 44 13 C 42.894531 13 42 13.894531 42 15 C 42 16.105469 42.894531 17 44 17 C 45.105469 17 46 16.105469 46 15 C 46 13.894531 45.105469 13 44 13 Z M 6 15 L 38 15 L 38 22 L 36 22 C 35.449219 22 35 22.449219 35 23 L 35 25 C 35 25.554688 34.554688 26 34 26 L 33 26 L 33 23 L 31 23 L 31 26 L 29 26 L 29 23 L 27 23 L 27 26 L 25 26 L 25 23 L 23 23 L 23 26 L 21 26 L 21 23 L 19 23 L 19 26 L 17 26 L 17 23 L 15 23 L 15 26 L 13 26 L 13 23 L 11 23 L 11 26 L 10 26 C 9.445313 26 9 25.554688 9 25 L 9 23 C 9 22.449219 8.550781 22 8 22 L 6 22 Z M 44 19 C 42.894531 19 42 19.894531 42 21 C 42 22.105469 42.894531 23 44 23 C 45.105469 23 46 22.105469 46 21 C 46 19.894531 45.105469 19 44 19 Z M 6 24 L 7 24 L 7 25 C 7 26.644531 8.355469 28 10 28 L 34 28 C 35.644531 28 37 26.644531 37 25 L 37 24 L 38 24 L 38 35 L 6 35 Z M 44 25 C 42.894531 25 42 25.894531 42 27 C 42 28.105469 42.894531 29 44 29 C 45.105469 29 46 28.105469 46 27 C 46 25.894531 45.105469 25 44 25 Z M 3.375 41 L 5.625 41 L 5.28125 42 L 3.71875 42 Z M 44.375 41 L 46.625 41 L 46.28125 42 L 44.71875 42 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e635e8 elementor-widget elementor-widget-heading\" data-id=\"7e635e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mini-oven<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7288af9 elementor-widget elementor-widget-text-editor\" data-id=\"7288af9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Op aanvraag bij de receptie<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec52031 e-con-full e-flex e-con e-child\" data-id=\"ec52031\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c56174 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3c56174\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#000000\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 25 3 C 15.622621 3 8 10.622621 8 20 L 8 25 L 7 25 C 5.3550302 25 4 26.35503 4 28 C 4 29.64497 5.3550302 31 7 31 L 8 31 C 8 37.712141 11.845821 44.111463 17.5625 46.898438 A 1.0001 1.0001 0 0 0 18 47 L 32 47 A 1.0001 1.0001 0 0 0 32.4375 46.898438 C 38.155132 44.111521 42 37.712974 42 31 L 43 31 C 44.64497 31 46 29.64497 46 28 C 46 26.35503 44.64497 25 43 25 L 42 25 L 42 20 C 42 19.065683 41.909682 18.151712 41.763672 17.255859 C 42.516774 15.684802 43.112451 14.322041 43.472656 13.228516 C 43.93158 11.835294 44.117645 10.733886 43.931641 9.7421875 C 43.745637 8.7504893 43.089046 7.960691 42.291016 7.4941406 C 41.928404 7.2821669 41.518958 7.1248011 41.089844 7.0527344 C 40.875286 7.0167009 40.656419 7.001668 40.435547 7.0117188 C 40.214674 7.0217695 39.991796 7.0569043 39.771484 7.1210938 C 39.005688 7.3442145 38.312856 7.8463626 37.587891 8.5761719 C 34.4773 5.1512281 29.985051 3 25 3 z M 25 5 C 29.49855 5 33.519477 6.9770659 36.267578 10.105469 C 34.862225 11.926431 33.176508 14.63468 30.933594 18.519531 L 29.707031 17.292969 A 1.0001 1.0001 0 0 0 28.984375 17 A 1.0001 1.0001 0 0 0 28.486328 17.142578 L 23.972656 19.851562 C 23.297202 19.132236 22.600373 18.73175 22 18.464844 L 22 11 C 22 10.477778 21.808671 9.9453899 21.431641 9.5683594 C 21.05461 9.1913289 20.522222 9 20 9 L 18 9 C 17.477778 9 16.94539 9.1913289 16.568359 9.5683594 C 16.191329 9.9453899 16 10.477778 16 11 L 16 18.457031 C 15.332416 18.745987 14.534899 19.17491 13.783203 20.070312 C 12.892938 21.130776 12.193816 22.718554 12.035156 25 L 10 25 L 10 20 C 10 11.703379 16.703379 5 25 5 z M 40.564453 8.9941406 C 40.781909 8.9739059 40.971371 9.0384137 41.283203 9.2207031 C 41.740673 9.4881528 41.882895 9.6639953 41.966797 10.111328 C 42.050697 10.558661 41.978217 11.36916 41.572266 12.601562 C 40.845172 14.808907 39.051401 18.394589 36.130859 23.716797 L 32.396484 19.982422 C 35.329853 14.883311 37.335219 11.782811 38.732422 10.263672 C 39.451639 9.481687 39.99506 9.1391948 40.332031 9.0410156 C 40.416274 9.0164709 40.491968 9.0008855 40.564453 8.9941406 z M 18 11 L 20 11 L 20 19.099609 A 1.0001 1.0001 0 0 0 20.683594 20.048828 C 21.196631 20.219841 21.98899 20.555772 22.679688 21.388672 C 23.268179 22.098324 23.806923 23.195573 23.955078 25 L 14.041016 25 C 14.186999 23.151004 14.730526 22.053355 15.316406 21.355469 C 16.001462 20.539446 16.779652 20.227746 17.316406 20.048828 A 1.0001 1.0001 0 0 0 18 19.099609 L 18 11 z M 40 14 L 37.369141 14.128906 C 37.022141 14.812906 37.354344 15.634 38.277344 15.5 C 39.200344 15.367 39.653 14.684 40 14 z M 37.763672 17.998047 L 35.134766 18.128906 C 34.787766 18.812906 35.118016 19.634 36.041016 19.5 C 36.964016 19.366 37.416672 18.682047 37.763672 17.998047 z M 28.845703 19.259766 L 34.585938 25 L 25.951172 25 C 25.846684 23.589957 25.538014 22.43117 25.095703 21.507812 L 28.845703 19.259766 z M 40 20.753906 L 40 25 L 37.708984 25 C 38.572479 23.432578 39.321937 22.041555 40 20.753906 z M 7 27 L 12.832031 27 A 1.0001 1.0001 0 0 0 13.158203 27 L 24.832031 27 A 1.0001 1.0001 0 0 0 25.158203 27 L 36.847656 27 A 1.0001 1.0001 0 0 0 37.179688 27 L 43 27 C 43.56503 27 44 27.43497 44 28 C 44 28.56503 43.56503 29 43 29 L 7 29 C 6.4349698 29 6 28.56503 6 28 C 6 27.43497 6.4349698 27 7 27 z M 10 31 L 40 31 C 40 36.875876 36.562392 42.548425 31.707031 45 L 18.292969 45 C 13.438599 42.548456 10 36.874722 10 31 z M 29 33 A 1.0001 1.0001 0 1 0 29 35 L 36 35 A 1.0001 1.0001 0 1 0 36 33 L 29 33 z M 16 36 A 1.0001 1.0001 0 1 0 16 38 L 23 38 A 1.0001 1.0001 0 1 0 23 36 L 16 36 z M 27 41 A 1.0001 1.0001 0 1 0 27 43 L 31 43 A 1.0001 1.0001 0 1 0 31 41 L 27 41 z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d69dd26 elementor-widget elementor-widget-heading\" data-id=\"d69dd26\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ontbijtmand  <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42ce6df elementor-widget elementor-widget-text-editor\" data-id=\"42ce6df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t18 \u20ac voor 2 personen (behalve juli en augustus)\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c18ab21 e-con-full e-flex e-con e-child\" data-id=\"c18ab21\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c8e5b0 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7c8e5b0\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 28.90625 8.96875 C 28.863281 8.976563 28.820313 8.988281 28.78125 9 C 28.40625 9.066406 28.105469 9.339844 28 9.703125 C 27.894531 10.070313 28.003906 10.460938 28.28125 10.71875 C 28.78125 11.21875 29.417969 11.71875 30.34375 11.875 C 31.097656 12 32.453125 11.96875 34.125 11.96875 C 34.164063 12.226563 34.1875 12.472656 34.25 12.84375 C 34.382813 13.632813 34.585938 14.75 34.84375 16 L 17.625 16 L 16.125 13 C 16.183594 12.996094 16.253906 13 16.3125 13 C 18.914063 13 20 12.292969 20 11.59375 C 20 10.992188 19.488281 10.992188 18.6875 11.09375 L 12.3125 11.09375 C 11.210938 11.09375 11 11.601563 11 12.5 C 11 14.800781 12.367188 14.039063 14.125 13.4375 L 15.875 17 L 13.53125 21.65625 C 12.429688 21.234375 11.246094 21 10 21 C 4.488281 21 0 25.488281 0 31 C 0 36.511719 4.488281 41 10 41 C 15.175781 41 19.4375 37.046875 19.9375 32 L 24 32 C 24.203125 31.996094 24.398438 31.929688 24.5625 31.8125 C 24.582031 31.804688 24.605469 31.792969 24.625 31.78125 C 24.636719 31.769531 24.644531 31.761719 24.65625 31.75 C 24.675781 31.742188 24.699219 31.730469 24.71875 31.71875 C 24.71875 31.707031 24.71875 31.699219 24.71875 31.6875 C 24.730469 31.675781 24.738281 31.667969 24.75 31.65625 C 24.785156 31.617188 24.816406 31.574219 24.84375 31.53125 L 35.53125 19.0625 C 35.730469 19.90625 35.972656 20.804688 36.21875 21.75 C 32.582031 23.25 30 26.832031 30 31 C 30 36.511719 34.488281 41 40 41 C 45.511719 41 50 36.511719 50 31 C 50 25.488281 45.511719 21 40 21 C 39.355469 21 38.734375 21.070313 38.125 21.1875 C 37.710938 19.566406 37.34375 18.046875 37.0625 16.75 C 36.679688 14.976563 36.386719 13.539063 36.21875 12.53125 C 36.132813 12.027344 36.101563 11.617188 36.0625 11.34375 C 36.042969 11.207031 36.007813 11.101563 36 11.03125 C 35.992188 10.960938 36 10.851563 36 11 C 36 10.449219 35.550781 10 35 10 C 32.5 10 31.230469 9.96875 30.65625 9.875 C 30.082031 9.78125 30.21875 9.78125 29.71875 9.28125 C 29.511719 9.058594 29.210938 8.945313 28.90625 8.96875 Z M 18.625 18 L 33.84375 18 L 24.21875 29.1875 Z M 17 19.25 L 22.375 30 L 19.9375 30 C 19.628906 26.867188 17.875 24.171875 15.34375 22.5625 Z M 10 23 C 10.933594 23 11.824219 23.144531 12.65625 23.4375 L 9.09375 30.5625 C 8.941406 30.875 8.960938 31.242188 9.148438 31.535156 C 9.332031 31.824219 9.652344 32.003906 10 32 L 17.9375 32 C 17.445313 35.953125 14.089844 39 10 39 C 5.570313 39 2 35.429688 2 31 C 2 26.570313 5.570313 23 10 23 Z M 40 23 C 44.429688 23 48 26.570313 48 31 C 48 35.429688 44.429688 39 40 39 C 35.570313 39 32 35.429688 32 31 C 32 27.742188 33.9375 24.96875 36.71875 23.71875 C 37.363281 26.050781 38.132813 28.597656 39.0625 31.3125 C 39.128906 31.703125 39.417969 32.015625 39.796875 32.113281 C 40.179688 32.210938 40.582031 32.078125 40.828125 31.769531 C 41.074219 31.460938 41.117188 31.039063 40.9375 30.6875 C 40.015625 27.992188 39.253906 25.441406 38.625 23.125 C 39.070313 23.046875 39.53125 23 40 23 Z M 14.4375 24.375 C 16.316406 25.632813 17.644531 27.644531 17.9375 30 L 11.625 30 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aff8a24 elementor-widget elementor-widget-heading\" data-id=\"aff8a24\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fietsverhuur<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad28aa1 elementor-widget elementor-widget-text-editor\" data-id=\"ad28aa1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t10 \u20ac ( van 15 juni tot 15 september )\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d6285f e-con-full e-flex e-con e-child\" data-id=\"1d6285f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7ab375 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a7ab375\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 50 50\" width=\"50px\" height=\"50px\"><path d=\"M 28 0 C 22.613281 0 18.230469 4.285156 18.03125 9.625 L 13.03125 11.90625 L 1.4375 6.09375 C 1.261719 6.007813 1.066406 5.976563 0.875 6 C 0.371094 6.0625 -0.00390625 6.492188 0 7 L 0 43 C -0.00390625 43.386719 0.214844 43.738281 0.5625 43.90625 L 12.5625 49.90625 C 12.839844 50.039063 13.160156 50.039063 13.4375 49.90625 L 25.03125 44.09375 L 37.59375 49.90625 C 37.875 50.03125 38.199219 50.019531 38.46875 49.875 L 49.46875 43.875 C 49.792969 43.703125 49.996094 43.367188 50 43 L 50 7 C 49.996094 6.652344 49.8125 6.328125 49.511719 6.148438 C 49.210938 5.96875 48.839844 5.960938 48.53125 6.125 L 37.84375 11.9375 C 37.933594 11.285156 38 10.640625 38 10 C 38 4.488281 33.511719 0 28 0 Z M 28 2 C 32.429688 2 36 5.570313 36 10 C 36 13.714844 33.863281 18.371094 31.65625 22.03125 C 29.832031 25.054688 28.578125 26.558594 28 27.28125 C 27.429688 26.582031 26.175781 25.140625 24.34375 22.125 C 22.25 18.675781 20.230469 14.296875 20.03125 10.59375 C 20.128906 10.339844 20.117188 10.058594 20 9.8125 C 20.101563 5.46875 23.632813 2 28 2 Z M 28 6 C 25.25 6 23 8.25 23 11 C 23 13.75 25.25 16 28 16 C 30.75 16 33 13.75 33 11 C 33 8.25 30.75 6 28 6 Z M 28 8 C 29.667969 8 31 9.332031 31 11 C 31 12.667969 29.667969 14 28 14 C 26.332031 14 25 12.667969 25 11 C 25 9.332031 26.332031 8 28 8 Z M 2 8.625 L 12.5625 13.90625 C 12.828125 14.03125 13.140625 14.03125 13.40625 13.90625 L 18.09375 11.78125 C 18.589844 15.78125 20.660156 19.867188 22.65625 23.15625 C 24.949219 26.933594 27.25 29.65625 27.25 29.65625 C 27.445313 29.878906 27.726563 30.003906 28.023438 29.996094 C 28.316406 29.992188 28.597656 29.855469 28.78125 29.625 C 28.78125 29.625 31.050781 26.859375 33.34375 23.0625 C 34.96875 20.367188 36.609375 17.160156 37.4375 13.9375 L 37.875 14 C 38.082031 14.019531 38.289063 13.976563 38.46875 13.875 L 48 8.6875 L 48 42.40625 L 37.96875 47.875 L 25.40625 42.09375 C 25.140625 41.96875 24.828125 41.96875 24.5625 42.09375 L 13 47.875 L 2 42.375 Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-823b7c3 elementor-widget elementor-widget-heading\" data-id=\"823b7c3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Keuze van locatie<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e873fb elementor-widget elementor-widget-text-editor\" data-id=\"2e873fb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t30 \u20ac (Als je wilt, kun je je accommodatie kiezen om het meeste uit je verblijf te halen).\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9db8c93 e-flex e-con-boxed e-con e-child\" data-id=\"9db8c93\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e198f30 elementor-widget elementor-widget-heading\" data-id=\"e198f30\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prijzen en beschikbaarheid van onze kampeerplaatsen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36b48bd elementor-widget elementor-widget-html\" data-id=\"36b48bd\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<thr-simpleblock categories=\"[12]\" day=\"samedi\" date=\"2022-04\" show-picture=\"true\" search-type=\"1\"><\/thr-simpleblock>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Boek uw vakantie GESTERILISEERDE LODGE Een bungalowtent huren in de Ari\u00e8ge 4 personen 2 slaapkamers 35 m\u00b2 LODGE OP PALEN OP CAMPING DE LA BESSE Deze kleine houten hutten op palen zijn van alle gemakken voorzien. Ze bevinden zich in het lager gelegen deel van de camping en bieden je de mogelijkheid om comfortabel van [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":16787,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16713","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verhuur van hutten in de Ari\u00e8ge Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge<\/title>\n<meta name=\"description\" content=\"Geniet van een verblijf in een hut op de 4-sterrencamping La Besse in de Ari\u00e8ge. Boek vandaag\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verhuur van hutten in de Ari\u00e8ge Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge\" \/>\n<meta property=\"og:description\" content=\"Geniet van een verblijf in een hut op de 4-sterrencamping La Besse in de Ari\u00e8ge. Boek vandaag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/\" \/>\n<meta property=\"og:site_name\" content=\"Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-12T08:25:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/\",\"url\":\"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/\",\"name\":\"Verhuur van hutten in de Ari\u00e8ge Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge\",\"isPartOf\":{\"@id\":\"https:\/\/camping-labesse.com\/nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg\",\"datePublished\":\"2024-05-07T09:48:20+00:00\",\"dateModified\":\"2026-07-12T08:25:08+00:00\",\"description\":\"Geniet van een verblijf in een hut op de 4-sterrencamping La Besse in de Ari\u00e8ge. Boek vandaag\",\"breadcrumb\":{\"@id\":\"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/#primaryimage\",\"url\":\"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg\",\"contentUrl\":\"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accommodatie\",\"item\":\"https:\/\/camping-labesse.com\/nl\/?page_id=16787\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canvas lodge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/camping-labesse.com\/nl\/#website\",\"url\":\"https:\/\/camping-labesse.com\/nl\/\",\"name\":\"Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge\",\"description\":\"Le domaine nature par excellence\",\"publisher\":{\"@id\":\"https:\/\/camping-labesse.com\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/camping-labesse.com\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/camping-labesse.com\/nl\/#organization\",\"name\":\"Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge\",\"url\":\"https:\/\/camping-labesse.com\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/camping-labesse.com\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/camping-labesse.com\/wp-content\/uploads\/2025\/02\/DSC_0702-scaled.jpg\",\"contentUrl\":\"https:\/\/camping-labesse.com\/wp-content\/uploads\/2025\/02\/DSC_0702-scaled.jpg\",\"width\":2560,\"height\":1696,\"caption\":\"Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge\"},\"image\":{\"@id\":\"https:\/\/camping-labesse.com\/nl\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verhuur van hutten in de Ari\u00e8ge Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge","description":"Geniet van een verblijf in een hut op de 4-sterrencamping La Besse in de Ari\u00e8ge. Boek vandaag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/","og_locale":"nl_NL","og_type":"article","og_title":"Verhuur van hutten in de Ari\u00e8ge Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge","og_description":"Geniet van een verblijf in een hut op de 4-sterrencamping La Besse in de Ari\u00e8ge. Boek vandaag","og_url":"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/","og_site_name":"Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge","article_modified_time":"2026-07-12T08:25:08+00:00","og_image":[{"url":"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/","url":"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/","name":"Verhuur van hutten in de Ari\u00e8ge Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge","isPartOf":{"@id":"https:\/\/camping-labesse.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/#primaryimage"},"image":{"@id":"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/#primaryimage"},"thumbnailUrl":"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg","datePublished":"2024-05-07T09:48:20+00:00","dateModified":"2026-07-12T08:25:08+00:00","description":"Geniet van een verblijf in een hut op de 4-sterrencamping La Besse in de Ari\u00e8ge. Boek vandaag","breadcrumb":{"@id":"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/#primaryimage","url":"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg","contentUrl":"https:\/\/camping-labesse.com\/wp-content\/uploads\/elementor\/thumbs\/cabane-qmuo8f6aj2j1nkc3r736jdajahq792c7sbj5mary50.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/camping-labesse.com\/nl\/accommodatie\/canvas-lodge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accommodatie","item":"https:\/\/camping-labesse.com\/nl\/?page_id=16787"},{"@type":"ListItem","position":2,"name":"Canvas lodge"}]},{"@type":"WebSite","@id":"https:\/\/camping-labesse.com\/nl\/#website","url":"https:\/\/camping-labesse.com\/nl\/","name":"Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge","description":"Le domaine nature par excellence","publisher":{"@id":"https:\/\/camping-labesse.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/camping-labesse.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/camping-labesse.com\/nl\/#organization","name":"Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge","url":"https:\/\/camping-labesse.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/camping-labesse.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/camping-labesse.com\/wp-content\/uploads\/2025\/02\/DSC_0702-scaled.jpg","contentUrl":"https:\/\/camping-labesse.com\/wp-content\/uploads\/2025\/02\/DSC_0702-scaled.jpg","width":2560,"height":1696,"caption":"Domaine de la Besse - Camping 4 \u00e9toiles en Ari\u00e8ge"},"image":{"@id":"https:\/\/camping-labesse.com\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/camping-labesse.com\/nl\/wp-json\/wp\/v2\/pages\/16713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camping-labesse.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/camping-labesse.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/camping-labesse.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/camping-labesse.com\/nl\/wp-json\/wp\/v2\/comments?post=16713"}],"version-history":[{"count":2,"href":"https:\/\/camping-labesse.com\/nl\/wp-json\/wp\/v2\/pages\/16713\/revisions"}],"predecessor-version":[{"id":20002,"href":"https:\/\/camping-labesse.com\/nl\/wp-json\/wp\/v2\/pages\/16713\/revisions\/20002"}],"up":[{"embeddable":true,"href":"https:\/\/camping-labesse.com\/nl\/wp-json\/wp\/v2\/pages\/16787"}],"wp:attachment":[{"href":"https:\/\/camping-labesse.com\/nl\/wp-json\/wp\/v2\/media?parent=16713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}